{"id":7390,"date":"2025-04-15T15:29:52","date_gmt":"2025-04-15T15:29:52","guid":{"rendered":"https:\/\/www.glasfaser-internet.info\/fiber-news\/?p=7390"},"modified":"2025-04-17T11:42:55","modified_gmt":"2025-04-17T11:42:55","slug":"telekom-kommt-quanteninternet-naeher","status":"publish","type":"post","link":"https:\/\/www.glasfaser-internet.info\/fiber-news\/telekom-kommt-quanteninternet-naeher","title":{"rendered":"Telekom kommt Quanteninternet n\u00e4her"},"content":{"rendered":"<p>Das Quanteninternet naht Schritt f\u00fcr Schritt. Die <a href=\"https:\/\/www.glasfaser-internet.info\/anbieter\/telekom-ftth.html\" data-internallinksmanager029f6b8e52c=\"14\" title=\"Glasfaser-Tarife der Telekom zeigen\">Deutsche Telekom<\/a> hat gemeinsam mit einem Partner ein Experiment via Glasfaser erfolgreich durchgef\u00fchrt.<!--more--><\/p>\n<p>&nbsp;<\/p>\n<div class=\"pic_r_cl\"><img decoding=\"async\" src=\"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-content\/uploads\/2025\/04\/glasfaser-photon.webp\" alt=\"Symbolbild Photon \u00fcber Glasfaser\" \/><\/p>\n<p>Symbolbild verschr\u00e4nktes Photon \u00fcber Glasfaser<\/p>\n<\/div>\n<h3>Feldexperiment auf Telekom-Glasfaser<\/h3>\n<p>Das Quanteninternet r\u00fcckt ein St\u00fcckchen n\u00e4her. Forscher der Deutsche Telekom Innovation Laboratories (T-Labs) haben gemeinsam mit Qunnect aus den USA einen weiteren Schritt in Richtung <a href=\"https:\/\/www.glasfaser-internet.info\/technik\/quanteninternet.html\" title=\"Was ist Quanteninternet?\">Quanteninternet<\/a> gemacht. Sie haben im Rahmen eines Feldexperiments auf der Telekom-Glasfaser eine stabile und mit 99 Prozent hochpr\u00e4zise \u00dcbertragung \u00fcber eine Distanz von 30 km demonstriert. <\/p>\n<p>&nbsp;<\/p>\n<p>Erfolgt ist der Versuch in der Glasfaserteststrecke des Quantum-Labs der T-Labs in Berlin. Dort wurden in einem Zeitraum von \u00fcber 17 Tage ohne Unterbrechung ein Feldexperiment mit so genannten verschr\u00e4nkten Photonen durchgef\u00fchrt. Das System hat sich hierbei automatisch an sich \u00e4ndernde Umgebungsbedingungen im Netzwerk angepasst. Die Ergebnisse dieser Pionierarbeit wurden am 31. M\u00e4rz 2025 auf der j\u00e4hrlichen OFC-Konferenz in San Francisco vorgestellt.<\/p>\n<p>&nbsp;<\/p>\n<p>In einem anderen Experiment hatten die Forscher Anfang des Jahres bereits polarisationsverschr\u00e4nkte Photonen dynamisch \u00fcber verschiedene Wege mit einer Gesamtl\u00e4nge von 82 Kilometer geroutet, w\u00e4hrend parallel der klassische Datenverkehr weiterlief. Hier erreichte man eine Genauigkeit von \u00fcber 92 Prozent. Es ist die l\u00e4ngste sogenannte High-Fidelity-Verschr\u00e4nkungsverteilung, die bisher erfolgreich \u00fcber verlegte Glasfasern durchgef\u00fchrt wurde. Sie belegt, dass ein paralleler Betrieb von klassischem Internet und Quanteninternet im Bereich des Machbaren ist. Genutzt wurde hierbei das sogenannte O-Band, w\u00e4hrend die klassische Daten\u00fcbertragung parallel im so genannten C-Band erfolgt ist.<\/p>\n<h3>Quanteninternet f\u00fcr sichere Daten\u00fcbertragungen<\/h3>\n<p>Die neuen Versuche belegen, dass die heutige Glasfaser bereit ist f\u00fcr das Quanteninternet. Es soll in Zukunft schnelle und sichere Verbindungen zu Quantenger\u00e4ten auf der ganzen Welt erm\u00f6glichen. Derzeit ist dies noch theoretischer Natur und Gegenstand der Forschung, bei der noch einige technische Herausforderungen zu meistern sind. Die j\u00fcngsten Erfolge sind aber ein entscheidender Schritt auf dem Weg zum Quanteninternet. Sie zeigen, wie die bestehende Telekommunikationsinfrastruktur auf Basis von Glasfaser die Quantentechnologien von morgen unterst\u00fctzen kann.<\/p>\n<h3>Hilfreiches zum Beitrag:<\/h3>\n<p>\u00bb <a href=\"https:\/\/www.glasfaser-internet.info\/technik\/quanteninternet.html\">mehr zum Thema Quanteninternet erfahren<\/a><br \/>\n\u00bb <a href=\"https:\/\/www.glasfaser-internet.info\/technik\/xs-gpon.html\">10 GBit\/s mit XS-PON Glasfaser<\/a><br \/>\n\u00bb <a href=\"https:\/\/www.glasfaser-internet.info\/faq\/was-ist-glasfaser.html\">Was ist Glasfaser?<\/a><\/p>\n<p>&nbsp;<\/p>\n<div class=\"quellenews\">\nQuelle: Deutsche Telekom<br \/>\nBild im Artikel: &copy; Glasfaser-Internet.info\n<\/div>\n<div style='text-align:center' class='yasr-auto-insert-visitor'><\/div>","protected":false},"excerpt":{"rendered":"<p>Das Quanteninternet naht Schritt f\u00fcr Schritt. Die Deutsche Telekom hat gemeinsam mit einem Partner ein Experiment via Glasfaser erfolgreich durchgef\u00fchrt.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","iawp_total_views":31,"footnotes":"","jetpack_post_was_ever_published":false,"_wp_rev_ctl_limit":""},"categories":[28,27,36],"tags":[119,3,1126],"class_list":["post-7390","post","type-post","status-publish","format-standard","hentry","category-telekom-ftth-provider","category-ftth-provider","category-technik","tag-deutsche-telekom","tag-glasfaser","tag-quanteninternet"],"views":205,"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":0,"sum_votes":0},"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/posts\/7390","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/comments?post=7390"}],"version-history":[{"count":4,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/posts\/7390\/revisions"}],"predecessor-version":[{"id":7419,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/posts\/7390\/revisions\/7419"}],"wp:attachment":[{"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/media?parent=7390"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/categories?post=7390"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/tags?post=7390"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}