{"id":7235,"date":"2025-02-23T17:24:47","date_gmt":"2025-02-23T17:24:47","guid":{"rendered":"https:\/\/www.glasfaser-internet.info\/fiber-news\/?p=7235"},"modified":"2025-02-23T17:24:47","modified_gmt":"2025-02-23T17:24:47","slug":"vodafone-neue-projekte-im-gigabit-bereich","status":"publish","type":"post","link":"https:\/\/www.glasfaser-internet.info\/fiber-news\/vodafone-neue-projekte-im-gigabit-bereich","title":{"rendered":"Vodafone: Neue Projekte im Gigabit-Bereich"},"content":{"rendered":"<p>In Deutschland realisiert <a href=\"https:\/\/www.glasfaser-internet.info\/anbieter\/vodafone-ftth.html\" data-internallinksmanager029f6b8e52c=\"15\" title=\"\u00dcbersicht der Vodafone Glasfaser-Tarife\">Vodafone<\/a> die Versorgung mit <a href=\"https:\/\/www.glasfaser-internet.info\/tarife\/glasfaser1000.html\" data-internallinksmanager029f6b8e52c=\"54\" title=\"Anbieter und Kosten f\u00fcr 1000 MBit\/s\">Gigabit<\/a>-Anschl\u00fcssen durch eigene Modernisierungsarbeiten sowie \u00fcber das Joint-Venture OXG, welches derzeit mit dem <a href=\"https:\/\/www.glasfaser-internet.info\/ausbau\/glasfaser-ausbau.html\" data-internallinksmanager029f6b8e52c=\"1\" title=\"alles zum aktuellen Stand des FTTH-Ausbaus\">Glasfaserausbau<\/a> in Heidelberg besch\u00e4ftigt ist.<!--more--><\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-content\/uploads\/2025\/01\/fiber-ausbau-telekom3.webp\" alt=\"Vodafone intensiviert den Glasfaserausbau in Baden-W\u00fcrttemberg\" title=\"Vodafone intensiviert den Glasfaserausbau in Baden-W\u00fcrttemberg\"><\/p>\n<h3>Upgrade des Kabelnetzes<\/h3>\n<p>Extra zur Modernisierung des eigenen Kabelnetzes greift der D\u00fcsseldorfer Netzbetreiber auf zwei verschiedene Ma\u00dfnahmen zur\u00fcck. So wird die Segmentierung eingesetzt, wenn am Verst\u00e4rkerpunkt eines Netzabschnitts zu wenig Bandbreite f\u00fcr die Nutzer vorhanden ist. Dadurch wird der Netzabschnitt weiter unterteilt, indem neue Glasfaserkabel verlegt werden sowie der bisherige Verst\u00e4rkerpunkt (VrP) durch einen Fiber Node (FN) ersetzt wird. <\/p>\n<p>&nbsp;<\/p>\n<p>Andererseits kommt es vor, dass zu wenig Bandbreite im Backbone, sprich an der Stelle, wo der regionale Backbone mit dem nationalen Backbone verbunden ist, zur Verf\u00fcgung steht. Dabei werden zus\u00e4tzliche Glasfaserleitungen hinzugeschaltet. Die Aufr\u00fcstung des Backbones ist jedoch begrenzt m\u00f6glich, da das Kabelnetz \u00fcber weniger Frequenzen verf\u00fcgt.<\/p>\n<h3>Netzmodernisierung in Calw<\/h3>\n<p>F\u00fcr die in Baden-W\u00fcrttemberg gelegene Gemeinde Calw sind zwei Bauprojekte erforderlich gewesen, um das Kabelnetz aufzur\u00fcsten. So surfen seit Ende Februar 951 Nutzer in Bald Wildbad schneller und stabiler im Netz des D\u00fcsseldorfer Netzbetreibers. <\/p>\n<h3>Netz-Upgrade im Zollernalbkreis<\/h3>\n<p>In Zollernalbkreis, welcher zur Region Neckar-Alb geh\u00f6rt, hat der D\u00fcsseldorfer zwei Bauprojekte umgesetzt, wobei die Modernisierung des Kabelnetzes einige Monate lang gedauert hat. Seit kurzem verf\u00fcgen 1.482 Nutzer in Stra\u00dfberg \u00fcber einen stabileren und leistungsf\u00e4higeren Kabelanschluss.<\/p>\n<h3>Aufr\u00fcstung im LK G\u00f6ppingen<\/h3>\n<p>Der D\u00fcsseldorfer Netzbetreiber hat im Landkreis G\u00f6ppingen eine einzelne Modernisierungsma\u00dfnahme angewandt, um das Kabelnetz aufzur\u00fcsten. F\u00fcr circa 523 Nutzer in Gingen an der Fils stehen seit Mitte Februar schnellere sowie stabilere Bandbreiten im Kabelnetz zur Verf\u00fcgung.<\/p>\n<h3>Glasfaseroffensive in Heidelberg<\/h3>\n<p>Das Joint-Venture aus Vodafone und Altice, genannt OXG, betreibt derzeit in Heidelberg eine Glasfaseroffensive. \u00dcber 14.000 Haushalte in Heidelberg erhalten einen <a href=\"https:\/\/www.glasfaser-internet.info\/ratgeber\/glasfaser-anschluss.html\" data-internallinksmanager029f6b8e52c=\"2\" title=\"alles \u00fcber Glasfaser-Anschl\u00fcsse erfahren\">Glasfaseranschluss<\/a> des Joint-Ventures. Finanziert wird der gro\u00dffl\u00e4chige Ausbau mit eigenen Mitteln. Neben den Tarifen des D\u00fcsseldorfer Telekommunikationsabieters, stehen den Nutzern Tarife anderer ISPs zur Verf\u00fcgung, da via <a href=\"https:\/\/www.glasfaser-internet.info\/technik\/open-access.html\" data-internallinksmanager029f6b8e52c=\"44\" title=\"OpenAccess\">Open Access<\/a> alternative Netzbetreiber Zugang zum Netz erhalten.<\/p>\n<p>&nbsp;<\/p>\n<p>Doch das ist nicht das einzige Projekt, mit dem sich das Joint-Venture besch\u00e4ftigt. Aufgrund eines gro\u00dfen Budgets im Milliardenbereich, plant es, circa sieben Millionen Glasfaseranschl\u00fcsse in den n\u00e4chsten sechs Jahren zu errichten. Um die 20% dieser Anschl\u00fcsse werden dort gebaut, wo bislang kein Netz von Vodafone vorhanden ist.<\/p>\n<h3>OXG: Anschluss von Wohnungen<\/h3>\n<p>Das Ausbauprojekt ist Teil der Glasfaser-Offensive in Heidelberg. In Kooperation mit der Baugenossenschaft Neu Heidelberg eG, beabsichtigt OXG 1.300 Wohnungen mit Glasfaser zu versorgen. Getreu dem Firmenname des Joint-Ventures, welches f\u00fcr \u201eOpen Access Glasfaser\u201c steht, erhalten alternative Netzbetreiber Zugang zum Glasfasernetz der Baugenossenschaft. Dadurch k\u00f6nnen die Bewohner aus einer Vielzahl von Tarifen w\u00e4hlen. <\/p>\n<h3>Hilfreiches zum Beitrag:<\/h3>\n<p>\u00bb <a href=\"https:\/\/www.glasfaser-internet.info\/vergleich\/glasfaser-tarife.html\">jetzt Glasfaser-Tarife vergleichen<\/a><br \/>\n\u00bb <a href=\"https:\/\/www.glasfaser-internet.info\/anbieter\/glasfaser-anbieter-uebersicht.html\">wichtige Glasfaser Anbieter im \u00dcberblick<\/a><\/p>\n<p>&nbsp;<\/p>\n<div class=\"quellenews\">\nQuellen: OXG, Vodafone<br \/>\nBild im Artikel: &copy; Glasfaser-Internet.info\n<\/div>\n<div style='text-align:center' class='yasr-auto-insert-visitor'><\/div>","protected":false},"excerpt":{"rendered":"<p>In Deutschland realisiert Vodafone die Versorgung mit Gigabit-Anschl\u00fcssen durch eigene Modernisierungsarbeiten sowie \u00fcber das Joint-Venture OXG, welches derzeit mit dem Glasfaserausbau in Heidelberg besch\u00e4ftigt ist.<\/p>\n","protected":false},"author":11,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","iawp_total_views":40,"footnotes":"","jetpack_post_was_ever_published":false,"_wp_rev_ctl_limit":""},"categories":[1,34,19,27],"tags":[39,1107,523,877,859,139,1108],"class_list":["post-7235","post","type-post","status-publish","format-standard","hentry","category-allgemein","category-anternativen","category-ausbau","category-ftth-provider","tag-glasfaser-ausbau","tag-goeppingen","tag-heidelberg","tag-modernisierung","tag-oxg","tag-vodafone","tag-zollernalbkreis"],"views":329,"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":0,"sum_votes":0},"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/posts\/7235","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/comments?post=7235"}],"version-history":[{"count":4,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/posts\/7235\/revisions"}],"predecessor-version":[{"id":7242,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/posts\/7235\/revisions\/7242"}],"wp:attachment":[{"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/media?parent=7235"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/categories?post=7235"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/tags?post=7235"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}