{"id":6867,"date":"2024-11-24T13:43:17","date_gmt":"2024-11-24T13:43:17","guid":{"rendered":"https:\/\/www.glasfaser-internet.info\/fiber-news\/?p=6867"},"modified":"2024-11-24T13:43:17","modified_gmt":"2024-11-24T13:43:17","slug":"vodafone-und-telekom-fortsetzung-der-breitband-offensive","status":"publish","type":"post","link":"https:\/\/www.glasfaser-internet.info\/fiber-news\/vodafone-und-telekom-fortsetzung-der-breitband-offensive","title":{"rendered":"Vodafone und Telekom: Fortsetzung der Breitband-Offensive"},"content":{"rendered":"<p>Auch wenn <a href=\"https:\/\/www.glasfaser-internet.info\/anbieter\/vodafone-ftth.html\" data-internallinksmanager029f6b8e52c=\"15\" title=\"\u00dcbersicht der Vodafone Glasfaser-Tarife\">Vodafone<\/a> \u00fcber das Joint-Venture OXG neue Glasfaser-Anschl\u00fcsse baut, r\u00fcstet der Netzbetreiber dennoch das Kabel-Glasfasernetz weiter auf. Die Telekom hingegen legt den Fokus vermehrt auf die eigene Glasfaser-Offensive.<!--more--><\/p>\n<h3>Ausbauprojekt am Taunus<\/h3>\n<p>Noch befindet sich das Glasfaser-Projekt des Bonner Netzbetreibers in der Planungsphase. Dabei sollen 20.000 Haushalte in Hofheim ans Glasfasernetz angeschlossen werden. Mit dem Ausbau des Glasfasernetzes in Hofheim ist nicht vor dem ersten Quartal 2026 zu rechnen, wobei in der Innenstadt zuerst ausgebaut wird. Danach setzt sich der Ausbau in den Stadtteilen Hofheim-Marxheim, -Diedenbergen und Wallau fort, was erst die darauffolgenden Jahre betrifft.<\/p>\n<h3>Ausbauprojekt in Waiblingen<\/h3>\n<p>In Waiblingen hat die <a href=\"https:\/\/www.glasfaser-internet.info\/anbieter\/telekom-ftth.html\" data-internallinksmanager029f6b8e52c=\"14\" title=\"Glasfaser-Tarife der Telekom zeigen\">Deutsche Telekom<\/a> bereits mit dem Ausbau des eigenen Glasfasernetzes angefangen, sodass f\u00fcr mehr wie 2.000 Haushalte und Gewerbetreibende Anschl\u00fcsse verf\u00fcgbar sind. Aufgrund des aus eigenen Mitteln finanzierten Ausbaus, werden in Waiblingen bislang das Krankenhaus, \u201eder Technologie- und Zukunftspark Hess, die Gewerbegebiete Ameisenb\u00fchl, Eisental und Waiblingen S\u00fcd, Gewerbegebiete Ameisenb\u00fchl, Eisental und Waiblingen S\u00fcd, das Pflegestift &#8222;Am K\u00e4tzenbach&#8220; sowie die Neubaugebiete Im Hohen Rain und Berg B\u00fcrg in Bittenfeld&#8220; mit Glasfaser versorgt. <\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-content\/uploads\/2023\/04\/glasfaser-telekom-1.webp\"><\/p>\n<p>&nbsp;<\/p>\n<p>Ein weiterer Ausbau von Waiblingen ist f\u00fcr das n\u00e4chste Fr\u00fchjahr angesetzt, bei dem der Bonner Netzbetreiber beabsichtigt, zus\u00e4tzliche 4.600 <a href=\"https:\/\/www.glasfaser-internet.info\/ratgeber\/glasfaser-anschluss.html\" data-internallinksmanager029f6b8e52c=\"2\" title=\"alles \u00fcber Glasfaser-Anschl\u00fcsse erfahren\">Glasfaseranschl\u00fcsse<\/a> auf der Korber H\u00f6he zu errichten. Der bevorstehende Ausbau wird mit eigenen Mitteln finanziert und findet in jedem Fall statt, was das Erreichen einer Vorvermarktungsquote er\u00fcbrigt.<\/p>\n<h3>Modernisierungsma\u00dfnahmen von Vodafone<\/h3>\n<p>Um mehr aus dem eigenen Kabel-Glasfasernetz herauszuholen, greift der D\u00fcsseldorfer Netzbetreiber auf Segmentierungsma\u00dfnahmen zur\u00fcck. Davon betroffen sind Gebiete, in denen ein hohes Datenaufkommen zu einem Flaschenhals f\u00fchrt. Dabei werden in die Netzsegmente weitere Glasfaser-Knotenpunkte installiert, sodass eine geringere Zahl an Nutzern innerhalb desselben Netzsegments zur selben Zeit aufs Internet zugreift. Aufgrund des h\u00f6heren Glasfaseranteils stehen gr\u00f6\u00dfere Bandbreiten f\u00fcr die Nutzer zur Verf\u00fcgung. <\/p>\n<p>&nbsp;<\/p>\n<div class=\"pic_l\"><img decoding=\"async\" src=\"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-content\/uploads\/2012\/02\/verteiler.jpg\"><\/div>\n<p>Falls die Segmentierung nichts gebracht hat, setzt Vodafone zus\u00e4tzlich auf den Ausbau von regionalen Backbone-Anbindungen. K\u00fcrzlich wurde ein neuer Backbone in Kiel errichtet, wovon circa 700 Haushalte mit Kabelanschluss Nutzen daraus schlagen. Den eigenen Angaben zufolge, ist das Festnetz \u201ewesentlich stabiler und leistungsst\u00e4rker\u201c geworden.<\/p>\n<p>&nbsp;<\/p>\n<p>Ebenso baute der D\u00fcsseldorfer Netzbetreiber einen neuen Backbone im Landkreis Kleve, welcher zum Regierungsbezirk D\u00fcsseldorf geh\u00f6rt. Dank dieser Ma\u00dfnahme, verf\u00fcgen \u00fcber 846 Haushalte in Kleve \u00fcber einen verbesserten Kabelanschluss.<\/p>\n<h3>Hilfreiches zum Beitrag:<\/h3>\n<p>\u00bb <a href=\"https:\/\/www.glasfaser-internet.info\/anbieter\/glasfaser-anbieter-uebersicht.html\">Glasfaser Anbieter im \u00dcberblick<\/a><br \/>\n\u00bb <a href=\"https:\/\/www.glasfaser-internet.info\/verfuegbarkeit\/glasfaser-verfuegbarkeit-testen.html\">Karte zur Glasfaser Verf\u00fcgbarkeit<\/a><\/p>\n<p>&nbsp;<\/p>\n<div class=\"quellenews\">\nQuellen: Deutsche Telekom, Vodafone<br \/>\nBilder im Artikel: &copy; Glasfaser-Internet.info\n<\/div>\n<div style='text-align:center' class='yasr-auto-insert-visitor'><\/div>","protected":false},"excerpt":{"rendered":"<p>Auch wenn Vodafone \u00fcber das Joint-Venture OXG neue Glasfaser-Anschl\u00fcsse baut, r\u00fcstet der Netzbetreiber dennoch das Kabel-Glasfasernetz weiter auf. Die Telekom hingegen legt den Fokus vermehrt auf die eigene Glasfaser-Offensive.<\/p>\n","protected":false},"author":11,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","iawp_total_views":11,"footnotes":"","jetpack_post_was_ever_published":false,"_wp_rev_ctl_limit":""},"categories":[1,34,19,28,27],"tags":[1070,1073,39,1071,1076,1072,6,139,1075,1074],"class_list":["post-6867","post","type-post","status-publish","format-standard","hentry","category-allgemein","category-anternativen","category-ausbau","category-telekom-ftth-provider","category-ftth-provider","tag-backbone","tag-diedenbergen","tag-glasfaser-ausbau","tag-hofheim","tag-kleve","tag-marxheim","tag-telekom","tag-vodafone","tag-waiblingen","tag-wallau"],"views":216,"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":0,"sum_votes":0},"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/posts\/6867","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/comments?post=6867"}],"version-history":[{"count":3,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/posts\/6867\/revisions"}],"predecessor-version":[{"id":6877,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/posts\/6867\/revisions\/6877"}],"wp:attachment":[{"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/media?parent=6867"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/categories?post=6867"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/tags?post=6867"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}