{"id":6657,"date":"2024-09-24T09:26:09","date_gmt":"2024-09-24T09:26:09","guid":{"rendered":"https:\/\/www.glasfaser-internet.info\/fiber-news\/?p=6657"},"modified":"2024-10-01T14:27:16","modified_gmt":"2024-10-01T14:27:16","slug":"telekom-knackt-marke-von-9-millionen-glasfaseranschluessen","status":"publish","type":"post","link":"https:\/\/www.glasfaser-internet.info\/fiber-news\/telekom-knackt-marke-von-9-millionen-glasfaseranschluessen","title":{"rendered":"Telekom knackt Marke von 9 Millionen Glasfaseranschl\u00fcssen"},"content":{"rendered":"<p>Die <a href=\"https:\/\/www.glasfaser-internet.info\/anbieter\/telekom-ftth.html\" data-internallinksmanager029f6b8e52c=\"14\" title=\"Glasfaser-Tarife der Telekom zeigen\">Deutsche Telekom<\/a> hat die Marke von 9 Millionen <a href=\"https:\/\/www.glasfaser-internet.info\/ratgeber\/glasfaser-anschluss.html\" data-internallinksmanager029f6b8e52c=\"2\" title=\"alles \u00fcber Glasfaser-Anschl\u00fcsse erfahren\">Glasfaseranschl\u00fcssen<\/a> geknackt. Somit k\u00f6nnen nun \u00fcber 9 Millionen Haushalte in Deutschland von besonders schnellem Internet profitieren.<!--more--><\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-content\/uploads\/2023\/04\/glasfaser-telekom-3.webp\" alt=\"Deutsche Telekom knackt 9 Millionen Glasfaser-Marke.\" title=\"Deutsche Telekom knackt 9 Millionen Glasfaser-Marke.\"><\/p>\n<h3>9-Millionen-Marke geknackt<\/h3>\n<p>Die Deutsche Telekom hat heute bekanntgegeben, dass man die Marke von 9 Millionen Glasfaseranschl\u00fcssen in Deutschland \u00fcberschritten hat. Durch die Ausbauaktivit\u00e4ten im August 2024 wurde die Grenze \u00fcbertroffen. Insgesamt sind nun 9,1 Millionen Haushalte mit einem Glasfaseranschluss der Telekom versorgt und k\u00f6nnen somit einen <a href=\"https:\/\/www.glasfaser-internet.info\/tarife\/glasfaser1000.html\">Tarif mit bis zu 1.000 Mbit\/s<\/a> buchen.<\/p>\n<p>&nbsp;<\/p>\n<p>Abdurazak Mudesir, Gesch\u00e4ftsf\u00fchrer Technologie der Telekom Deutschland, freut sich \u00fcber das Erreichen der Zahl von 9 Millionen Anschl\u00fcssen: \u201eDie Marke von neun Millionen Glasfaserhaushalten ist ein wichtiger Meilenstein. Ich bin stolz, dass mein Team die Ausbaugeschwindigkeit in einem schwierigen Umfeld hochh\u00e4lt. Daf\u00fcr braucht es Leidenschaft, Energie und Ausdauer. Andere diskutieren, wir bauen. Und ich freue mich, dass wir Tag f\u00fcr Tag mehr Menschen die M\u00f6glichkeit geben, Internet in Lichtgeschwindigkeit zu erleben.\u201c<\/p>\n<h3>\u00dcber 36 Millionen versorgte Haushalte<\/h3>\n<p>Neben den nun \u00fcber 9 Millionen Glasfaserhaushalten, k\u00f6nnen \u00fcber 30 Millionen einen Tarif mit bis zu 250 Mbit\/s bei der Telekom buchen. F\u00fcr mehr als 36 Millionen Haushalte stehen Tarife mit bis zu 100 Mbit\/s zur Verf\u00fcgung. Viele von diesen sollen in den kommenden Jahren ebenfalls mit einem Glasfaseranschluss versorgt werden, da die Telekom das Ausbautempo weiter hochhalten m\u00f6chte. Dann besteht auch hier die M\u00f6glichkeit, einen der <a href=\"https:\/\/www.glasfaser-internet.info\/fiber-news\/telekom-startet-neue-glasfaser-tarife-bis-2-000-mbit-s\" title=\"Telekom startet neue Glasfaser-Tarife bis 2.000 Mbit\/s\">neuen Glasfaser-Tarife der Telekom bis 2.000 Mbit\/s<\/a> zu buchen. Bei diesen liegt die <a href=\"https:\/\/www.glasfaser-internet.info\/speed\/glasfaser-upload.html\" data-internallinksmanager029f6b8e52c=\"9\" title=\"mehr zum Thema Upload bei Glasfaser-Tarifen erfahren\">Upload<\/a>-Geschwindigkeit immer halb so hoch wie die Downloads. Beispielsweise sind im mittleren Tarif <a href=\"https:\/\/www.glasfaser-internet.info\/tarife\/glasfaser500-600.html\" data-internallinksmanager029f6b8e52c=\"52\" title=\"alle Anbieter und Preise f\u00fcr Glasfaser mit 500-600 MBit\">600 Mbit\/s<\/a> im Download und <a href=\"https:\/\/www.glasfaser-internet.info\/tarife\/glasfaser300.html\" data-internallinksmanager029f6b8e52c=\"53\" title=\"alle Anbieter und Preise f\u00fcr Glasfaser mit 300 MBit\">300 Mbit\/s<\/a> im Upload m\u00f6glich.<\/p>\n<p>&nbsp;<\/p>\n<p>Gefragt sind hohe Datenraten unter anderem beim Streaming. Dies erfreut sich weiterhin gro\u00dfer Beliebtheit, wie sich die Top-5-Anwendungen des August im Telekom-Netz zeigen. Hier liegt YouTube vor Netflix, Amazon Prime Video, Instagram und Tiktok. Bei den Uploads springt iCloud von Platz vier auf eins und verdr\u00e4ngt die Google APIs auf den vierten Platz. Auf Platz zwei liegt Amazon Web Services. Platz drei nimmt Microsoft Teams ein, Platz f\u00fcnf geht an Discord.<\/p>\n<h3>Hilfreiches zum Beitrag:<\/h3>\n<p>\u00bb <a href=\"https:\/\/www.glasfaser-internet.info\/verfuegbarkeit\/glasfaser-verfuegbarkeit-testen.html\">Karte zur Glasfaser Verf\u00fcgbarkeit &#8211; jetzt testen<\/a><br \/>\n\u00bb <a href=\"https:\/\/www.glasfaser-internet.info\/tarife\/glasfaser-prepaid.html\">Gibt es Glasfaser auch Preapaid?<\/a><\/p>\n<p>&nbsp;<\/p>\n<div class=\"quellenews\">\nQuelle: Deutsche Telekom<br \/>\nBild im Artikel: &copy; Glasfaser-Internet.info\n<\/div>\n<div style='text-align:center' class='yasr-auto-insert-visitor'><\/div>","protected":false},"excerpt":{"rendered":"<p>Die Deutsche Telekom hat die Marke von 9 Millionen Glasfaseranschl\u00fcssen geknackt. Somit k\u00f6nnen nun \u00fcber 9 Millionen Haushalte in Deutschland von besonders schnellem Internet profitieren.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","iawp_total_views":12,"footnotes":"","jetpack_post_was_ever_published":false,"_wp_rev_ctl_limit":""},"categories":[1,19,28,27],"tags":[1040,9,6],"class_list":["post-6657","post","type-post","status-publish","format-standard","hentry","category-allgemein","category-ausbau","category-telekom-ftth-provider","category-ftth-provider","tag-august-2024","tag-glasfaserausbau","tag-telekom"],"views":238,"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":0,"sum_votes":0},"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/posts\/6657","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/comments?post=6657"}],"version-history":[{"count":4,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/posts\/6657\/revisions"}],"predecessor-version":[{"id":6666,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/posts\/6657\/revisions\/6666"}],"wp:attachment":[{"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/media?parent=6657"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/categories?post=6657"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/tags?post=6657"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}