{"id":6264,"date":"2024-03-06T07:42:08","date_gmt":"2024-03-06T07:42:08","guid":{"rendered":"https:\/\/www.glasfaser-internet.info\/fiber-news\/?p=6264"},"modified":"2024-03-06T10:17:31","modified_gmt":"2024-03-06T10:17:31","slug":"berlin-neue-vereinbarung-zwischen-pyur-und-der-wgli","status":"publish","type":"post","link":"https:\/\/www.glasfaser-internet.info\/fiber-news\/berlin-neue-vereinbarung-zwischen-pyur-und-der-wgli","title":{"rendered":"Berlin: Neue Vereinbarung zwischen P\u0178UR und der WGLi"},"content":{"rendered":"<p>Die WGLi geht mit der Tele Columbus eine neue Vereinbarung ein. Alle Wohnungen erhalten bis zum Ende des Jahrzehnts einen echten <a href=\"https:\/\/www.glasfaser-internet.info\/ratgeber\/glasfaser-anschluss.html\" data-internallinksmanager029f6b8e52c=\"2\" title=\"alles \u00fcber Glasfaser-Anschl\u00fcsse erfahren\">Glasfaseranschluss<\/a>.<!--more--><\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-content\/uploads\/2020\/09\/ausbau1.jpg\" alt=\"Kooperation gest\u00e4rkt zwischen P\u0178UR und der Berliner WGLi: Vollglasfaserversorgung bis 2030\" title=\"Kooperation gest\u00e4rkt zwischen P\u0178UR und der Berliner WGLi: Vollglasfaserversorgung bis 2030\"><\/p>\n<p>&nbsp;<\/p>\n<p>Die Tele Columbus versorgt seit mehreren Jahren die Wohnungen der WGLi mit Internet, wobei nun eine Netzaufr\u00fcstung hinzukommt. Die erweiterte Kooperation kommentierte Christian Biechteler, Chief Sales Officer Housing Industry &amp; Infrastructure und Vorstandsmitglied bei Berliner Netzbetreiber wie folgt: \u201eGemeinsam schlagen wir nun ein weiteres Kapitel unserer bew\u00e4hrten Partnerschaft auf (..). Wenn es um den Ausbau einer modernen Glasfaserinfrastruktur auf Basis offener Netze geht, bleiben wir f\u00fcr die Wohnungswirtschaft erster Ansprechpartner.\u201c<\/p>\n<h3>Ausdehnung der Kooperation<\/h3>\n<p>Die Kooperation zwischen dem Berliner Netzbetreiber und der Berliner Wohnungsgenossenschaft WGLi Lichtenberg eG ist nichts Neues. Denn der Berliner Netzbetreiber versorgt alle Wohnungen der WGLi \u00fcber die Marke <a href=\"https:\/\/www.glasfaser-internet.info\/anbieter\/pyur.html\">P\u0178UR mit Gigabit-Internet<\/a>. Jedoch handelt es sich dabei um keine Vollglasfaserversorgung, sondern um FTTB \u201eFiber-To-The-Building\u201c. Aktuell stehen den Bewohnern Geschwindigkeiten von bis zu <a href=\"https:\/\/www.glasfaser-internet.info\/tarife\/glasfaser1000.html\" data-internallinksmanager029f6b8e52c=\"54\" title=\"Anbieter und Kosten f\u00fcr 1000 MBit\/s\">1 Gbit<\/a> pro Sekunde zur Verf\u00fcgung. <\/p>\n<p>&nbsp;<\/p>\n<p>Im Zuge der Netzaufr\u00fcstung, werden \u00fcber 10.000 Wohnungen mit <a href=\"https:\/\/www.glasfaser-internet.info\/faq\/ftth-vs-glasfaser.html\">FTTH<\/a> \u201eFiber-To-The-Home\u201c versorgt, sodass zuk\u00fcnftig weitaus h\u00f6here Geschwindigkeiten realisierbar sind. Die Aufr\u00fcstung betrifft alle drei Dienste, welche vom Berliner Netzbetreiber angeboten werden, n\u00e4mlich Internet, <a href=\"https:\/\/www.glasfaser-internet.info\/iptv\/glasfaser-und-iptv.html\">TV<\/a> sowie Telefon. Aller Voraussicht nach wird die Vollglasfaserversorgung der Best\u00e4nde der WGLi 2029 erreicht sein. <\/p>\n<p>&nbsp;<\/p>\n<p>Thomas Kleindienst, im Vorstand der WGLi, betont in seinem Pressestatement die sich daraus ergebenden Vorteile f\u00fcr die Mieter: \u201eDurch das Ausbauvorhaben k\u00f6nnen zuk\u00fcnftig alle Wohnungen mit <a href=\"https:\/\/www.glasfaser-internet.info\/speed\/geschwindigkeit-glasfaser.html\">Geschwindigkeiten<\/a> \u00fcber das aktuell bereits verf\u00fcgbare Gigabit-Tempo hinaus beliefert werden. Von diesem Zugewinn profitieren alle unsere Mitglieder und Mieter beim Streaming und mobilen Arbeiten. Wir freuen uns auf eine <a href=\"https:\/\/www.glasfaser-internet.info\/faq\/ftth-vs-glasfaser.html\" data-internallinksmanager029f6b8e52c=\"8\" title=\"Was ist FTTH?\">FTTH<\/a>-Glasfaserversorgung mit hoher Zuverl\u00e4ssigkeit und stabilen Bandbreiten von P\u0178UR.\u201c <\/p>\n<h3>Open-Access-Modell<\/h3>\n<p>Die Kooperation beinhaltet au\u00dferdem ein <a href=\"https:\/\/www.glasfaser-internet.info\/technik\/open-access.html\" data-internallinksmanager029f6b8e52c=\"44\" title=\"OpenAccess\">Open-Access<\/a>-Modell, was der Konkurrenz Zugriff auf die Glasfasernetze der WGLi erm\u00f6glicht. Die Konkurrenten k\u00f6nnen per zus\u00e4tzlicher Geb\u00fchr den Mietern weitere Dienstleistungen sowie alternative Internet-Tarife anbieten.<\/p>\n<h3>Hilfreiches zum Beitrag:<\/h3>\n<p>\u00bb <a href=\"https:\/\/www.glasfaser-internet.info\/verfuegbarkeit\/glasfaser-verfuegbarkeit-testen.html\">Karte zur Glasfaser Verf\u00fcgbarkeit<\/a><br \/>\n\u00bb <a href=\"https:\/\/www.glasfaser-internet.info\/alternativen\/uebersicht.html\">das sind die Alternativen zu Glasfaser<\/a><br \/>\n\u00bb <a href=\"https:\/\/www.glasfaser-internet.info\/hardware\/glasfaser-router.html\">Glasfaser-Router | \u00dcbersicht und Ratgeber<\/a><\/p>\n<div class=\"quellenews\">\nQuelle: Tele Columbus<br \/>\nBild im Artikel: &copy; Glasfaser-Internet.info\n<\/div>\n<div style='text-align:center' class='yasr-auto-insert-visitor'><\/div>","protected":false},"excerpt":{"rendered":"<p>Die WGLi geht mit der Tele Columbus eine neue Vereinbarung ein. Alle Wohnungen erhalten bis zum Ende des Jahrzehnts einen echten Glasfaseranschluss.<\/p>\n","protected":false},"author":11,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","iawp_total_views":130,"footnotes":"","jetpack_post_was_ever_published":false,"_wp_rev_ctl_limit":""},"categories":[1,34,19,27,31],"tags":[174,235,541,526,989],"class_list":["post-6264","post","type-post","status-publish","format-standard","hentry","category-allgemein","category-anternativen","category-ausbau","category-ftth-provider","category-sonstige","tag-ausbau","tag-berlin","tag-pyur","tag-tele-columbus","tag-wgli"],"views":603,"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":0,"sum_votes":0},"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/posts\/6264","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/comments?post=6264"}],"version-history":[{"count":4,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/posts\/6264\/revisions"}],"predecessor-version":[{"id":6280,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/posts\/6264\/revisions\/6280"}],"wp:attachment":[{"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/media?parent=6264"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/categories?post=6264"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/tags?post=6264"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}