{"id":5760,"date":"2023-09-13T21:17:23","date_gmt":"2023-09-13T21:17:23","guid":{"rendered":"https:\/\/www.glasfaser-internet.info\/fiber-news\/?p=5760"},"modified":"2023-09-14T06:26:37","modified_gmt":"2023-09-14T06:26:37","slug":"niedersachen-ausbau-durch-die-deutsche-glasfaser","status":"publish","type":"post","link":"https:\/\/www.glasfaser-internet.info\/fiber-news\/niedersachen-ausbau-durch-die-deutsche-glasfaser","title":{"rendered":"Niedersachen: Ausbau durch die Deutsche Glasfaser"},"content":{"rendered":"<p>Am 13. September unterschrieben Vertreter der Deutschen Glasfaser zusammen mit dem nieders\u00e4chsischen Wirtschaftsminister einen Kooperationsvertrag, um den <a href=\"https:\/\/www.glasfaser-internet.info\/ausbau\/glasfaser-ausbau.html\" data-internallinksmanager029f6b8e52c=\"1\" title=\"alles zum aktuellen Stand des FTTH-Ausbaus\">Glasfaser-Ausbau<\/a> in Niedersachsen voranzutreiben.<!--more--><\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-content\/uploads\/2021\/11\/glasfaser-ausbau-1.webp\" alt=\"Deutsche Glasfaser steigert Glasfaserausbau in Niedersachsen\" title=\"Deutsche Glasfaser steigert Glasfaserausbau in Niedersachsen\"><\/p>\n<p>&nbsp;<\/p>\n<p>In der Vergangenheit baute die <a href=\"https:\/\/www.glasfaser-internet.info\/anbieter\/deutsche-glasfaser.html\">Deutsche Glasfaser<\/a> circa 450.000 Anschl\u00fcsse in Niedersachsen, wobei das Telekommunikationsunternehmen aktuell 110.000 zus\u00e4tzliche Anschl\u00fcsse herstellt. Mit dem neuen Kooperationsvertrag beabsichtigt der Netzbetreiber bis 2027 950.000 neue Internet-Anschl\u00fcsse zu errichten. Finanziert wird der geplante Ausbau mit eigenen Mitteln, sodass f\u00fcr die Landesregierung keine Kosten entstehen. Laut dem Wirtschaftsminister Olaf Lies, seien dies \u201egute Nachrichten f\u00fcr Niedersachsen, denn das Unternehmen steht beispielhaft daf\u00fcr, dass der Markt hochdynamisch ist. Unsere Vereinbarung zeigt: Wir sind offen f\u00fcr alternative Verlegetechniken, Transparenz beim Ausbau und unterst\u00fctzen Unternehmen und nieders\u00e4chsische Kommunen in der Zusammenarbeit. So beschleunigen wir den Ausbau in Niedersachsen.\u201c<br \/>\n&nbsp;<br \/>\nAndreas Pfisterer, CEO der Deutschen Glasfaser verwies indes darauf, dass der Netzbetreiber Wert auf eine gute Kooperation mit der Landesregierung legt: \u201eWir stehen zu Niedersachsen und festigen mit dem Letter of Intent \u00fcber den <a href=\"https:\/\/www.glasfaser-internet.info\/ausbau\/glasfaser-ausbau.html\">Ausbau<\/a> von 950.000 Haushalten bis Ende 2027 unsere enge Partnerschaft. Als f\u00fchrender Digital-Versorger legen wir mit dem Glasfaserausbau das Fundament f\u00fcr Wohlstand und Lebensqualit\u00e4t in unserer Gesellschaft und machen die l\u00e4ndlichen und suburbanen Regionen Niedersachsens zukunftssicher. Dabei setzen wir insbesondere auf eine enge Zusammenarbeit mit allen Beteiligten \u2013 von der Landespolitik \u00fcber die Kommunen bis zu den B\u00fcrgerinnen und B\u00fcrgern.\u201c<\/p>\n<h3>Landesregierung f\u00fcr eine Beschleunigung der Bauvorhaben<\/h3>\n<p>Die nieders\u00e4chsische Landesregierung sowie die teilnehmenden Kommunen hatten in der Vergangenheit den Breitbandausbau mit einer knappen Milliarde Euro gef\u00f6rdert. Allerdings erweisen sich Engp\u00e4sse in der Bauwirtschaft sowie die Genehmigungsbeh\u00f6rden als Stolperstein. Aufgrund dessen setzt sich die Landesregierung f\u00fcr effizientere Baumethoden, f\u00fcr genormte sowie vereinfachende Gehnemigungsverfahren und der Aufstockung des Genehmigungspersonals ein. Mithilfe der Ma\u00dfnahmen m\u00f6chte die Landesregierung die \u00fcppig vorhandenen Investitionsmittel sinnvoll ausgeben.<\/p>\n<h3>Breitband-Versorgung in Niedersachsen<\/h3>\n<p>Laut dem <a href=\"https:\/\/gigabitgrundbuch.bund.de\/cln_131\/GIGA\/DE\/_Home\/start.html\" target=\"_blank\" rel=\"nofollow noopener\">Gigabit-Grundbuch der Bundesregierung<\/a> rangiert Niedersachsen auf Platz 2, was die Fl\u00e4chenl\u00e4nder angeht. Bez\u00fcglich den Glasfaser-Zuwachsraten, kann kein anderes Bundesland mithalten, was somit Niedersachsen den ersten Platz beschert. Die Breitbandversorung kann als sehr gut bezeichnet werden, denn 75% der Haushalte verf\u00fcgen \u00fcber einen <a href=\"https:\/\/www.glasfaser-internet.info\/tarife\/glasfaser1000.html\" data-internallinksmanager029f6b8e52c=\"54\" title=\"Anbieter und Kosten f\u00fcr 1000 MBit\/s\">Gigabit<\/a>-Anschluss. Dabei betr\u00e4gt der Anteil an <a href=\"https:\/\/www.glasfaser-internet.info\/ratgeber\/glasfaser-anschluss.html\" data-internallinksmanager029f6b8e52c=\"2\" title=\"alles \u00fcber Glasfaser-Anschl\u00fcsse erfahren\">Glasfaser-Anschl\u00fcssen<\/a> 41%. Die derzeit stattfindenden sowie geplanten Ausbauprojekte werden die Abdeckung von Gigabit-Anschl\u00fcssen auf 80% erh\u00f6hen, im Bereich Glasfaser sind sogar 60% zu erwarten.<\/p>\n<h3>Hilfreiches zum Beitrag:<\/h3>\n<p>\u00bb <a href=\"https:\/\/www.glasfaser-internet.info\/verfuegbarkeit\/glasfaser-verfuegbarkeit-testen.html\">hier Glasfaser Verf\u00fcgbarkeit testen<\/a><\/p>\n<div class=\"quellenews\">Quelle: <a href=\"https:\/\/www.glasfaser-internet.info\/anbieter\/deutsche-glasfaser.html\" data-internallinksmanager029f6b8e52c=\"18\" title=\"FTTH-Tarife der Deutschen Glasfaser zeigen\">Deutsche Glasfaser<\/a><br \/>\nBild im Artikel: &copy; Glasfaser-Internet.info<\/div>\n<div style='text-align:center' class='yasr-auto-insert-visitor'><\/div>","protected":false},"excerpt":{"rendered":"<p>Am 13. September unterschrieben Vertreter der Deutschen Glasfaser zusammen mit dem nieders\u00e4chsischen Wirtschaftsminister einen Kooperationsvertrag, um den Glasfaser-Ausbau in Niedersachsen voranzutreiben.<\/p>\n","protected":false},"author":11,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","iawp_total_views":8,"footnotes":"","jetpack_post_was_ever_published":false,"_wp_rev_ctl_limit":""},"categories":[1,34,19,359,27],"tags":[],"class_list":["post-5760","post","type-post","status-publish","format-standard","hentry","category-allgemein","category-anternativen","category-ausbau","category-dt-glasfaser","category-ftth-provider"],"views":385,"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":0,"sum_votes":0},"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/posts\/5760","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/comments?post=5760"}],"version-history":[{"count":4,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/posts\/5760\/revisions"}],"predecessor-version":[{"id":5764,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/posts\/5760\/revisions\/5764"}],"wp:attachment":[{"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/media?parent=5760"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/categories?post=5760"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/tags?post=5760"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}