{"id":5054,"date":"2023-02-24T19:21:29","date_gmt":"2023-02-24T19:21:29","guid":{"rendered":"https:\/\/www.glasfaser-internet.info\/fiber-news\/?p=5054"},"modified":"2023-03-03T14:17:26","modified_gmt":"2023-03-03T14:17:26","slug":"glasfaserausbau-zu-koeln-david-gegen-goliath","status":"publish","type":"post","link":"https:\/\/www.glasfaser-internet.info\/fiber-news\/glasfaserausbau-zu-koeln-david-gegen-goliath","title":{"rendered":"Glasfaserausbau zu K\u00f6ln: David gegen Goliath"},"content":{"rendered":"<p>Im Raum K\u00f6ln \u00fcberbaut die Telekom gerade das Netz von <a href=\"https:\/\/www.glasfaser-internet.info\/anbieter\/netcologne.html\" data-internallinksmanager029f6b8e52c=\"17\" title=\"Netcologne Glasfaser-Tarife zeigen\">NetCologne<\/a> und wirft dem lokalen Anbieter minderwertige Technik vor.<!--more--> <\/p>\n<h3>Vereinbarung zwischen NetCologne und ZTE<\/h3>\n<p>2017 begann NetCologne durch Einsatz der <a href=\"https:\/\/www.glasfaser-internet.info\/technik\/gfast.html\" data-internallinksmanager029f6b8e52c=\"5\" title=\"Was ist Gfast?\">G.fast<\/a>-Technik ein FTTB-Netz \u201eFibre-To-The-Bulding\u201c in K\u00f6ln zu errichten. Hierbei unterschrieben NetCologne sowie ZTE gemeinsam einen Vertrag, wonach ZTE NetCologne nicht nur G.fast-DPUs (Distribution Point Units) und -Terminals zur Verf\u00fcgung stellte, sondern mit Netzwerkkomponenten versorgte. Als Beweis f\u00fcr h\u00f6here Geschwindigkeiten innerhalb des FTTB-Netz stellten die beiden Partner \u00f6ffentlich die Messdaten zur Verf\u00fcgung, wonach die Download-Geschwindigkeit bei 1,6 <a href=\"https:\/\/www.glasfaser-internet.info\/tarife\/glasfaser1000.html\" data-internallinksmanager029f6b8e52c=\"54\" title=\"Anbieter und Kosten f\u00fcr 1000 MBit\/s\">Gigabit<\/a> pro Sekunde und die <a href=\"https:\/\/www.glasfaser-internet.info\/speed\/glasfaser-upload.html\" data-internallinksmanager029f6b8e52c=\"9\" title=\"mehr zum Thema Upload bei Glasfaser-Tarifen erfahren\">Upload<\/a>-Geschwindigkeit bei 0,2 Gigabit pro Sekunde lag. Bez\u00fcglich der Geschwindigkeiten lassen sich mit einem FTTB-Netz keine so hohen Datenraten wie mit <a href=\"https:\/\/www.glasfaser-internet.info\/faq\/ftth-vs-glasfaser.html\" data-internallinksmanager029f6b8e52c=\"8\" title=\"Was ist FTTH?\">FTTH<\/a> erreichen, sodass in der Summe die Downloadrate plus die Uploadrate meist einen Gigabit pro Sekunde ergibt.<\/p>\n<p>&nbsp;<\/p>\n<p>NetCologne selbst ist als Telekommunikationsunternehmen vornehmlich in K\u00f6ln, Bonn, Leverkusen, Aachen, D\u00fcren, D\u00fcsseldorf und Neuss t\u00e4tig. Recherchen zu folge, betr\u00e4gt die Zahl der eigenen Festnetzanschl\u00fcsse 458.000, wobei lediglich 20% davon FTTB oder <a href=\"https:\/\/www.glasfaser-internet.info\/faq\/ftth-vs-glasfaser.html\">FTTH-Anschl\u00fcsse<\/a> darstellen. Allerdings werde NetCologne nun &#8222;bestehende FTTB-Infrastruktur in den n\u00e4chsten Jahren sukzessive Richtung FTTH weiterbauen und auch die Inhouse-Leitungen zunehmend verglasen&#8220;.<\/p>\n<h3>Ziele der Telekom<\/h3>\n<p>Die Ziele der Telekom stehen allerdings diametral zu den <a href=\"https:\/\/www.glasfaser-internet.info\/fiber-news\/ueberbau-beeintraechtigt-glasfaserausbau\">Appellen des VATM, \u00dcberbau tunlichst zu vermeiden<\/a>. So gab die Telekom 2022 bekannt, bis 2025 circa 100.000 <a href=\"https:\/\/www.glasfaser-internet.info\/ratgeber\/glasfaser-anschluss.html\" data-internallinksmanager029f6b8e52c=\"2\" title=\"alles \u00fcber Glasfaser-Anschl\u00fcsse erfahren\">FTTH-Anschl\u00fcsse<\/a> in K\u00f6ln zu bauen. Damit sind alleine im Download Geschwindigkeiten von ein Gigabit pro Sekunde und mehr m\u00f6glich.<\/p>\n<h3>Konfliktpotenzial: \u00dcberbau<\/h3>\n<p>Auch die NetCologne empfindet den \u00dcberbau als unn\u00f6tiges \u00dcbel und kommentierte die Ziele beziehungsweise Aktivit\u00e4ten der Telekom damit, dass dies \u201ekein Einzelfall und auch in anderen St\u00e4dten Praxis\u201c sei. Au\u00dferdem seien dies keine Ausbaut\u00e4tigkeiten, welche die Telekom vornehme, \u201esondern schlicht \u00dcberbau eines vorhandenen Netzes durch eine konkurrierende Infrastruktur.\u201c<\/p>\n<p>&nbsp;<\/p>\n<p>Allerdings betrachtet die Telekom das FTTB-Netz der NetCologne als \u00fcberholt und rechtfertigt ihre Ziele in K\u00f6ln mit dem Bau eines eigenen FTTH-Netz: &#8222;Wenn ich dann h\u00f6re, wie sich ein Herr von Lepel [Chef von NetCologne] dar\u00fcber erz\u00fcrnt, dass wir ihn \u00fcberbauen&#8220;, \u00e4u\u00dferte Tim H\u00f6ttges, Chef der Teleom am 23. Februar 2023. &#8222;Der baut keine Glasfaser bis zum Kunden, bis in die Wohnungen hinein. Was habe ich denn von FTTB? Nichts! Wir wollen doch Glasfaser mit 1 GBit haben.&#8220; F\u00fcr die <a href=\"https:\/\/www.glasfaser-internet.info\/ausbau\/telekom-ftth-ausbau.html\">Telekom ist der Glasfaserausbau<\/a> beziehungsweise \u00dcberbau beschlossene Sache, denn NetCologne h\u00e4tte es vers\u00e4umt, sich auf die neueste Glasfasertechnik zu konzentrieren: &#8222;Wir bauen da jetzt, weil die Netcologne da nicht baut, wenn er [Chef von NetCologne] sich da \u00fcberbaut f\u00fchlt, dann ist das sein Vers\u00e4umnis, weil er es nicht geschafft hat, Glasfaser bis zum Kunden zu bringen. Und das tun wir jetzt.&#8220;<\/p>\n<h3>Hilfreiches zum Beitrag:<\/h3>\n<p>\u00bb <a href=\"https:\/\/www.glasfaser-internet.info\/hardware\/glasfaser-router.html\">Glasfaser-Router | \u00dcbersicht und Ratgeber<\/a><br \/>\n\u00bb <a href=\"https:\/\/www.glasfaser-internet.info\/anbieter\/glasfaser-anbieter-uebersicht.html\">Glasfaser Anbieter im \u00dcberblick<\/a><\/p>\n<div class=\"quellenews\">Quelle: Golem.de<\/div>\n<div style='text-align:center' class='yasr-auto-insert-visitor'><\/div>","protected":false},"excerpt":{"rendered":"<p>Im Raum K\u00f6ln \u00fcberbaut die Telekom gerade das Netz von NetCologne und wirft dem lokalen Anbieter minderwertige Technik vor.<\/p>\n","protected":false},"author":11,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","iawp_total_views":14,"footnotes":"","jetpack_post_was_ever_published":false,"_wp_rev_ctl_limit":""},"categories":[1,34,19,28,27,29],"tags":[9,94,49,6,301],"class_list":["post-5054","post","type-post","status-publish","format-standard","hentry","category-allgemein","category-anternativen","category-ausbau","category-telekom-ftth-provider","category-ftth-provider","category-netcologne","tag-glasfaserausbau","tag-koln","tag-netcologne-2","tag-telekom","tag-ueberbau"],"views":667,"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":0,"sum_votes":0},"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/posts\/5054","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/comments?post=5054"}],"version-history":[{"count":4,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/posts\/5054\/revisions"}],"predecessor-version":[{"id":5098,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/posts\/5054\/revisions\/5098"}],"wp:attachment":[{"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/media?parent=5054"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/categories?post=5054"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/tags?post=5054"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}