{"id":4993,"date":"2023-02-15T11:03:16","date_gmt":"2023-02-15T11:03:16","guid":{"rendered":"https:\/\/www.glasfaser-internet.info\/fiber-news\/?p=4993"},"modified":"2023-02-15T11:03:16","modified_gmt":"2023-02-15T11:03:16","slug":"die-glasfaserprojekte-des-joint-ventures-ugg","status":"publish","type":"post","link":"https:\/\/www.glasfaser-internet.info\/fiber-news\/die-glasfaserprojekte-des-joint-ventures-ugg","title":{"rendered":"Die Glasfaserprojekte des Joint-Ventures UGG"},"content":{"rendered":"<p>VATM interviewte Jens Prautzsch, CEO von <a href=\"https:\/\/www.glasfaser-internet.info\/anbieter\/unsere-gruene-glasfaser.html\" data-internallinksmanager029f6b8e52c=\"46\" title=\"Was ist Unsere Gr\u00fcne Glasfaser?\">Unsere Gr\u00fcne Glasfaser<\/a> (<a href=\"https:\/\/www.glasfaser-internet.info\/anbieter\/unsere-gruene-glasfaser.html\" data-internallinksmanager029f6b8e52c=\"46\" title=\"Was ist Unsere Gr\u00fcne Glasfaser?\">UGG<\/a>) sowie Investor J\u00f6rg Spanier, Co-Head Infrastructure in M\u00fcnchen bei Allianz Capital Partners zum Thema <a href=\"https:\/\/www.glasfaser-internet.info\/ausbau\/glasfaser-ausbau.html\" data-internallinksmanager029f6b8e52c=\"1\" title=\"alles zum aktuellen Stand des FTTH-Ausbaus\">Glasfaserausbau<\/a> in Deutschland.<!--more--><\/p>\n<h3>Ziele der UGG<\/h3>\n<p>Das im Jahr 2021 gegr\u00fcndete Joint-Venture UGG, welches zur Allianz und Telef\u00f3nica Gruppe geh\u00f6rt, hat es sich zum Ziel gemacht, \u201efl\u00e4chendeckende <a href=\"https:\/\/www.glasfaser-internet.info\/faq\/ftth-vs-glasfaser.html\">FTTH<\/a>-Netze\u201c zu errichten. \u00c4hnlich wie <a href=\"https:\/\/www.glasfaser-internet.info\/anbieter\/deutsche-glasfaser.html\" data-internallinksmanager029f6b8e52c=\"18\" title=\"FTTH-Tarife der Deutschen Glasfaser zeigen\">Deutsche Glasfaser<\/a>, konzentriert sich UGG auf l\u00e4ndliche Regionen, also auf Gemeinden mit circa 10.000 Haushalten. In den n\u00e4chsten Jahren wolle man circa 2 Millionen Haushalte ans Glasfasernetz anschlie\u00dfen und dabei bis zu 50.000 Km lange Glasfaserkabel verlegen.<\/p>\n<p>&nbsp;<\/p>\n<p>Dank der Beteiligung der Allianz mit 50% an UGG, steht ein finanzstarker Partner beiseite, sodass f\u00fcr die kommenden Projekte bis zu 5 Milliarden Euro an Investitionsvolumen vorhanden sind. Letztes Jahr konnte UGG mit \u00fcber 300 Gemeinden Vereinbarungen bez\u00fcglich des <a href=\"https:\/\/www.glasfaser-internet.info\/ausbau\/glasfaser-ausbau.html\">Glasfaserausbaus<\/a> treffen.<\/p>\n<p>&nbsp;<\/p>\n<p>Ein gro\u00dfes Plus bei UGG ist, dass es \u00fcber einen langen Atem verf\u00fcgt. So erw\u00e4hnte Prautzsch: \u201eIch sage allen Gemeinden und Gesch\u00e4ftspartnern immer, dass wir \u2018gekommen sind, um zu bleiben\u2018. UGG bedeutet: Telef\u00f3nica \u201aGlasfaser-Know-how\u2018 powered by Allianz. Dabei steht die \u201aPower\u2018 nicht nur f\u00fcr leistungsstarke Glasfaserverbindungen, sondern auch f\u00fcr Finanzst\u00e4rke und Erfahrung. Das er\u00f6ffnet uns auch im Ausbau viele Vorteile gegen\u00fcber dem Wettbewerb.\u201c So kann es sich UGG erlauben, ohne Vorvermarktungsquote sofort mit dem Glasfaserausbau zu beginnen. Da das Glasfasernetz von UGG \u00fcber <a href=\"https:\/\/www.glasfaser-internet.info\/technik\/open-access.html\" data-internallinksmanager029f6b8e52c=\"44\" title=\"OpenAccess\">Open Access<\/a> f\u00fcr andere Netzbetreiber zug\u00e4nglich ist, kann sich der Kunde f\u00fcr einen Internetserviceprovider seiner Wahl entscheiden.<\/p>\n<h3>Engagement der Allianz<\/h3>\n<p>Bei der Allianz handelt es sich um einen der gr\u00f6\u00dften Infrastrukturinvestoren der Welt. Versicherte der Allianz ziehen Nutzen aus den Investitionen, indem sie Zugang zum ultraschnellem Internet erhalten und die erwirtschafteten Ertr\u00e4ge aus den Investitionen als Pensionsr\u00fccklage dienen. So hat die Allianz in den letzten 15 Jahren \u00fcber 25 Milliarden Euro in Infrastrukturprojekte gesteckt, wovon etliche Milliarden in die digitale Infrastruktur geflossen sind. Die Investitionen in UGG wertet Spanier als Erfolg: \u201eWenn man bedenkt, welche Herausforderungen das junge Team der UGG in den ersten 1,5 Jahren gemeistert hat, so kann man von einem sehr erfolgreichen Start sprechen. Die Nachwirkungen der Corona-Pandemie, der Krieg in der Ukraine und die damit verbundene Inflation und Lieferkettenprobleme, all das hat den Markt durcheinandergewirbelt. Als langfristiger Infrastrukturinvestor, der in mehreren anderen Glasfaserausbauprojekten engagiert ist, sind wir gewohnt, auch in anspruchsvollen Rahmenbedingungen zu agieren.\u201c<\/p>\n<h3>Hilfreiches zum Beitrag:<\/h3>\n<p>\u00bb <a href=\"https:\/\/www.glasfaser-internet.info\/verfuegbarkeit\/glasfaser-verfuegbarkeit-testen.html\">Glasfaser Karte<\/a><br \/>\n\u00bb <a href=\"https:\/\/www.glasfaser-internet.info\/anbieter\/glasfaser-anbieter-uebersicht.html\">Glasfaser Anbieter im \u00dcberblick<\/a><\/p>\n<div class=\"quellenews\">Quelle: VATM<\/div>\n<div style='text-align:center' class='yasr-auto-insert-visitor'><\/div>","protected":false},"excerpt":{"rendered":"<p>VATM interviewte Jens Prautzsch, CEO von Unsere Gr\u00fcne Glasfaser (UGG) sowie Investor J\u00f6rg Spanier, Co-Head Infrastructure in M\u00fcnchen bei Allianz Capital Partners zum Thema Glasfaserausbau in Deutschland.<\/p>\n","protected":false},"author":11,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","iawp_total_views":30,"footnotes":"","jetpack_post_was_ever_published":false,"_wp_rev_ctl_limit":""},"categories":[1,34,19,27,32,31],"tags":[286,9,591,196,480,188],"class_list":["post-4993","post","type-post","status-publish","format-standard","hentry","category-allgemein","category-anternativen","category-ausbau","category-ftth-provider","category-interviews","category-sonstige","tag-allianz","tag-glasfaserausbau","tag-laendliche-gebiete","tag-telefonica","tag-ugg","tag-vatm"],"views":775,"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":1,"sum_votes":5},"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/posts\/4993","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/comments?post=4993"}],"version-history":[{"count":3,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/posts\/4993\/revisions"}],"predecessor-version":[{"id":5010,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/posts\/4993\/revisions\/5010"}],"wp:attachment":[{"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/media?parent=4993"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/categories?post=4993"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/tags?post=4993"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}