{"id":4894,"date":"2023-01-19T14:06:01","date_gmt":"2023-01-19T14:06:01","guid":{"rendered":"https:\/\/www.glasfaser-internet.info\/fiber-news\/?p=4894"},"modified":"2023-01-20T09:29:39","modified_gmt":"2023-01-20T09:29:39","slug":"gesobau-und-tele-columbus-verstaerken-zusammenarbeit","status":"publish","type":"post","link":"https:\/\/www.glasfaser-internet.info\/fiber-news\/gesobau-und-tele-columbus-verstaerken-zusammenarbeit","title":{"rendered":"GESOBAU und Tele Columbus verst\u00e4rken Zusammenarbeit"},"content":{"rendered":"<p>Berlins f\u00fchrender <a href=\"https:\/\/www.glasfaser-internet.info\/anbieter\/glasfaser-anbieter-uebersicht.html\" data-internallinksmanager029f6b8e52c=\"37\" title=\"Welche Glasfaser-Anbieter gibt es?\">Glasfaseranbieter<\/a>, die Tele Columbus, erh\u00e4lt im Zuge eines \u00f6ffentlichen Vergabeverfahrens den Zuschlag, ab Herbst 2023 die Wohnungen der GESOBAU AG mit Glasfaser zu versorgen.<!--more--><\/p>\n<h3>Ausbauarbeiten der GESOBAU AG<\/h3>\n<p>Ab November 2023 werden 25.000 Wohnungen der GESOBAU AG nacheinander mit Glasfaser versorgt. Dabei handelt es sich um Wohnungen, die sich im M\u00e4rkischen Viertel (Reinickendorf) und Schillerh\u00f6he (Mitte) befinden. Abgesehen von superschnellem Internet mit bis zu einem <a href=\"https:\/\/www.glasfaser-internet.info\/tarife\/glasfaser1000.html\" data-internallinksmanager029f6b8e52c=\"54\" title=\"Anbieter und Kosten f\u00fcr 1000 MBit\/s\">Gigabit<\/a> pro Sekunde, wird \u00fcber die <a href=\"https:\/\/www.glasfaser-internet.info\/ratgeber\/glasfaser-anschluss.html\" data-internallinksmanager029f6b8e52c=\"2\" title=\"alles \u00fcber Glasfaser-Anschl\u00fcsse erfahren\">FTTH-Anschl\u00fcsse<\/a> <a href=\"https:\/\/www.glasfaser-internet.info\/iptv\/glasfaser-und-iptv.html\">hochaufl\u00f6sendes Fernsehen<\/a> sowie Telefon der Marke P\u0178UR verf\u00fcgbar sein.<\/p>\n<p>&nbsp;<\/p>\n<p>F\u00fcr die Signalumstellung auf <a href=\"https:\/\/www.glasfaser-internet.info\/faq\/ftth-vs-glasfaser.html\">FTTH<\/a> realisiert die Tele Columbus die Neustrukturierung und technische Aufr\u00fcstung der Hausverteilnetze. So tauscht die Tele Columbus Antennen und Multimediadosen aus. Zus\u00e4tzlich l\u00e4sst das Unternehmen die Verteilanlagen in den Kellern f\u00fcr die zuk\u00fcnftige Glasfaserversorgung umbauen.<\/p>\n<p>&nbsp;<\/p>\n<p>Die Umr\u00fcstung des Wohnungsbestands ist laut der GESOBAU AG essentiell, was deren Vorstand, Christian Wilkens wie folgt kommentiert: \u201eEine zukunftssichere digitale Grundversorgung ist zunehmend ein entscheidendes Kriterium f\u00fcr attraktiven Wohnraum. Mit dem Ausbau der Vollglasfaserversorgung in unserem Bestand unterst\u00fctzen wir in Zeiten flexiblerer Arbeitsmodelle und steigender Mediennutzung die digitale Kommunikation und f\u00f6rdern digitales Wohnen. Wir schaffen damit einen echten Mehrwert f\u00fcr unsere Mieter*innen.\u201c<\/p>\n<h3>Netze als Open Access Modell<\/h3>\n<p>Laut der abgeschlossenen Vereinbarung zwischen der Tele Columbus und GESOBAU AG, stehen die Glasfasernetze auf Basis von \u201e<a href=\"https:\/\/www.glasfaser-internet.info\/technik\/open-access.html\" data-internallinksmanager029f6b8e52c=\"44\" title=\"OpenAccess\">Open Access<\/a>\u201c der Konkurrenz zur Verf\u00fcgung. Dadurch entfallen etwaige Bauma\u00dfnahmen. Sobald die Ausbauarbeiten abgeschlossen sind, k\u00f6nnen die Bewohner einen Vertrag bei <a href=\"https:\/\/www.glasfaser-internet.info\/anbieter\/pyur.html\">P\u0178UR<\/a> buchen oder zwischen <a href=\"https:\/\/www.glasfaser-internet.info\/anbieter\/o2-telefonica.html\">O2<\/a> beziehungsweise <a href=\"https:\/\/www.glasfaser-internet.info\/anbieter\/1und1-glasfaser.html\">1&amp;1<\/a> w\u00e4hlen.<\/p>\n<p>&nbsp;<\/p>\n<p>Zur Kooperation zwischen der GESOBAU AG und der Tele Columbus \u00e4u\u00dferte sich R\u00fcdiger Schmidt, Chief Sales Officer Housing Industry &amp; Infrastructure bei Tele Columbus: \u201eWir blicken hochmotiviert auf unsere erweiterte Partnerschaft mit der GESOBAU und die anstehenden Aufgaben. Durch unsere Vereinbarung stellen wir sicher, dass in jeder Wohnung f\u00fcr jeden Bewohner eine Fernseh \u2013 und Internetinfrastruktur mit h\u00f6chster Leistungsf\u00e4higkeit zur Verf\u00fcgung steht. Die Entscheidung f\u00fcr einen konsequenten <a href=\"https:\/\/www.glasfaser-internet.info\/ausbau\/glasfaser-ausbau.html\" data-internallinksmanager029f6b8e52c=\"1\" title=\"alles zum aktuellen Stand des FTTH-Ausbaus\">Glasfaserausbau<\/a> wird sich f\u00fcr alle Beteiligten auszahlen.\u201c<\/p>\n<div class=\"quellenews\">Quelle: Tele Columbus<\/div>\n<div style='text-align:center' class='yasr-auto-insert-visitor'><\/div>","protected":false},"excerpt":{"rendered":"<p>Berlins f\u00fchrender Glasfaseranbieter, die Tele Columbus, erh\u00e4lt im Zuge eines \u00f6ffentlichen Vergabeverfahrens den Zuschlag, ab Herbst 2023 die Wohnungen der GESOBAU AG mit Glasfaser zu versorgen.<\/p>\n","protected":false},"author":11,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","iawp_total_views":34,"footnotes":"","jetpack_post_was_ever_published":false,"_wp_rev_ctl_limit":""},"categories":[1,34,19,27,31],"tags":[235,541,526,772],"class_list":["post-4894","post","type-post","status-publish","format-standard","hentry","category-allgemein","category-anternativen","category-ausbau","category-ftth-provider","category-sonstige","tag-berlin","tag-pyur","tag-tele-columbus","tag-wohnungen"],"views":893,"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":0,"sum_votes":0},"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/posts\/4894","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/comments?post=4894"}],"version-history":[{"count":4,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/posts\/4894\/revisions"}],"predecessor-version":[{"id":4913,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/posts\/4894\/revisions\/4913"}],"wp:attachment":[{"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/media?parent=4894"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/categories?post=4894"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/tags?post=4894"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}