{"id":4621,"date":"2022-11-21T09:51:08","date_gmt":"2022-11-21T09:51:08","guid":{"rendered":"https:\/\/www.glasfaser-internet.info\/fiber-news\/?p=4621"},"modified":"2022-11-21T09:51:08","modified_gmt":"2022-11-21T09:51:08","slug":"din-ausbauverfahren-soll-standardisiert-werden","status":"publish","type":"post","link":"https:\/\/www.glasfaser-internet.info\/fiber-news\/din-ausbauverfahren-soll-standardisiert-werden","title":{"rendered":"DIN: Ausbauverfahren soll standardisiert werden"},"content":{"rendered":"<p>Ein wichtiger Schritt zur Standardisierung moderner minimalinvasiver Verlegemethoden beim <a href=\"https:\/\/www.glasfaser-internet.info\/ausbau\/glasfaser-ausbau.html\" data-internallinksmanager029f6b8e52c=\"1\" title=\"alles zum aktuellen Stand des FTTH-Ausbaus\">Glasfaserausbau<\/a> ist dank einen neuen DIN-Entwurfs nun gemacht.<!--more--><\/p>\n<h3>DIN f\u00fcr minimalinvasive Verlegemethoden<\/h3>\n<p>Wie die <a href=\"https:\/\/www.glasfaser-internet.info\/anbieter\/deutsche-glasfaser.html\" data-internallinksmanager029f6b8e52c=\"18\" title=\"FTTH-Tarife der Deutschen Glasfaser zeigen\">Deutsche Glasfaser<\/a> mitgeteilt hat, wurde ein wichtiger Schritt zum schnelleren Glasfaserausbau in Deutschland gemacht. Der Ausschuss Bauwesen des Deutschen Instituts f\u00fcr Normung (DIN) hat den Entwurf einer Norm f\u00fcr so genannte <a href=\"https:\/\/www.glasfaser-internet.info\/technik\/trenching.html\" data-internallinksmanager029f6b8e52c=\"48\" title=\"Trenching\">Trenching<\/a>-, Fr\u00e4s- und <a href=\"https:\/\/www.glasfaser-internet.info\/technik\/trenching.html\" data-internallinksmanager029f6b8e52c=\"48\" title=\"Trenching\">Pflugverfahren<\/a> zur Legung von Leerrohrinfrastrukturen und Glasfaserkabeln f\u00fcr Telekommunikationsnetze (DIN 18220) verabschiedet. Dies kann als Vorzeichen f\u00fcr einen entscheidenden Durchbruch bei der Standardisierung moderner minimalinvasiver Verlegemethoden beim Glasfaserausbau angesehen werden.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201eWir begr\u00fc\u00dfen die Initiative des Deutschen Instituts f\u00fcr Normung ausdr\u00fccklich. Als Pioniere des Glasfaserausbaus setzen wir seit \u00fcber zehn Jahren moderne Verlegemethoden f\u00fcr die schnelle und effiziente Glasfaserversorgung ein. Wir freuen uns, dass unser bew\u00e4hrtes Verfahren zum Branchenstandard werden soll. Das ist ein deutliches Zeichen, dass wir mit unserem Ansatz richtig liegen\u201c, sagt Andreas Pfisterer, CEO der Deutsche Glasfaser Unternehmensgruppe. \u201eDas Bekenntnis des Deutschen Instituts f\u00fcr Normung zu modernen Verlegemethoden schafft Sicherheit f\u00fcr alle am Glasfaserausbau Beteiligten. Wir als Branche k\u00f6nnen den Glasfaserausbau nochmals deutlich beschleunigen. Dem Ziel der Bundesregierung, Deutschland bis 2030 fl\u00e4chendeckend mit Glasfaser zu versorgen, r\u00fccken wir so ein gro\u00dfes St\u00fcck n\u00e4her.\u201c<\/p>\n<h3>Einf\u00fchrung eines modernen Regelwerks f\u00fcr die Verlegung von Telekommunikations-Infrastruktur<\/h3>\n<p>Bereits seit 2020 engagiert sich Deutsche Glasfaser in der Expertengruppe des Deutschen Instituts f\u00fcr Normung, um eine Vereinheitlichung im Glasfaserausbau zu erreichen. Das Ziel des Gremiums ist die Einf\u00fchrung eines modernen Regelwerks f\u00fcr die Verlegung von Telekommunikations-Infrastruktur in Deutschland. Hierbei ist die neu erfolgte Ver\u00f6ffentlichung des DIN-Entwurfs ein wichtiger Meilenstein auf dem Weg zum rechtssicheren Einsatz minimalinvasiver Methoden von Glasfsaser und Co.<\/p>\n<p>&nbsp;<\/p>\n<p>Der Ende dieser Woche neu ver\u00f6ffentlichte Entwurf f\u00fcr die Normierung gibt Anhaltspunkte f\u00fcr die Vorbereitung, Anwendung und Dokumentation von modernen Verlegemethoden sowie auch \u00fcber die Wiederherstellung der Oberfl\u00e4chen. Bis Mitte Januar 2023 kann der neue Entwurf nun kommentiert werden und es besteht die M\u00f6glichkeit des Einbringens von \u00c4nderungsantr\u00e4gen. Diese wird das zust\u00e4ndige Gremium ber\u00fccksichtigen, bevor die DIN 18220 dann final verabschiedet wird. Mehr als 30 Gremienmitglieder aus Wissenschaft und Forschung sowie \u00d6ffentlicher Hand und Wirtschaft haben seit Ende 2020 an dem Regelwerk gearbeitet.<\/p>\n<h3>Hilfreiches zum Beitrag:<\/h3>\n<p>\u00bb <a href=\"https:\/\/www.glasfaser-internet.info\/hardware\/glasfaser-router.html\">Glasfaser-Router | \u00dcbersicht und Ratgeber<\/a><br \/>\n\u00bb <a href=\"https:\/\/www.glasfaser-internet.info\/anbieter\/glasfaser-anbieter-uebersicht.html\">Glasfaser Anbieter im \u00dcberblick<\/a><\/p>\n<div class=\"quellenews\">\nQuelle: Deutsche Glasfaser\n<\/div>\n<div style='text-align:center' class='yasr-auto-insert-visitor'><\/div>","protected":false},"excerpt":{"rendered":"<p>Ein wichtiger Schritt zur Standardisierung moderner minimalinvasiver Verlegemethoden beim Glasfaserausbau ist dank einen neuen DIN-Entwurfs nun gemacht.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","iawp_total_views":7,"footnotes":"","jetpack_post_was_ever_published":false,"_wp_rev_ctl_limit":""},"categories":[19,359,36],"tags":[68],"class_list":["post-4621","post","type-post","status-publish","format-standard","hentry","category-ausbau","category-dt-glasfaser","category-technik","tag-deutsche-glasfaser"],"views":511,"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":0,"sum_votes":0},"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/posts\/4621","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/comments?post=4621"}],"version-history":[{"count":4,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/posts\/4621\/revisions"}],"predecessor-version":[{"id":4632,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/posts\/4621\/revisions\/4632"}],"wp:attachment":[{"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/media?parent=4621"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/categories?post=4621"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/tags?post=4621"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}