{"id":3379,"date":"2021-12-11T12:18:42","date_gmt":"2021-12-11T12:18:42","guid":{"rendered":"https:\/\/www.glasfaser-internet.info\/fiber-news\/?p=3379"},"modified":"2025-08-11T14:54:13","modified_gmt":"2025-08-11T14:54:13","slug":"deutsche-glasfaser-und-freistaat-bayern-planen-550-000-glasfaseranschluesse","status":"publish","type":"post","link":"https:\/\/www.glasfaser-internet.info\/fiber-news\/deutsche-glasfaser-und-freistaat-bayern-planen-550-000-glasfaseranschluesse","title":{"rendered":"Deutsche Glasfaser und Freistaat Bayern planen 550.000 Glasfaseranschl\u00fcsse"},"content":{"rendered":"<p><a href=\"https:\/\/www.glasfaser-internet.info\/anbieter\/deutsche-glasfaser.html\" data-internallinksmanager029f6b8e52c=\"18\" title=\"FTTH-Tarife der Deutschen Glasfaser zeigen\">Deutsche Glasfaser<\/a> hat heute bekanntgegeben, dass man bis Ende 2025 etwa 550.000 Haushalte in Bayern mit Glasfaser versorgen will. Der Ausbau wird vorrangig eigenwirtschaftlich erfolgen, aber von der Regierung des Freistaats unterst\u00fctzt.<!--more--><br \/>\nStaatsminister der Finanzen und f\u00fcr Heimat, und Thorsten Dirks, der CEO von Deutsche Glasfaser, geeinigt.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-content\/uploads\/2021\/12\/glasfaser-netzausbau.webp\" alt=\"Glasfaser-Netzausbau\"><\/p>\n<h3>Glasfaser f\u00fcr Bayern<\/h3>\n<p>Rund 550.000 Haushalte im Freistaat Bayern sollen bis Ende 2025 Glasfaser bekommen. Dies hat die <a href=\"https:\/\/www.glasfaser-internet.info\/anbieter\/deutsche-glasfaser.html\">Deutsche Glasfaser<\/a> Holding GmbH, ein f\u00fchrender Anbieter f\u00fcr den Fiber-Netzausbau speziell im l\u00e4ndlichen Raum, heute bekanntgegeben. Den vorrangig eigenwirtschaftlichen Ausbau und die Anwendung moderner Verlegeverfahren durch das Unternehmen wird die Regierung des Freistaats unterst\u00fctzen. Auf eine entsprechende Absichtserkl\u00e4rung (Letter of Intent [LOI]) haben sich Albert F\u00fcracker, der Bayerische Staatsminister der Finanzen und f\u00fcr Heimat, und Thorsten Dirks, der CEO von Deutsche Glasfaser, geeinigt.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201eDer erfolgreiche Breitbandausbau ist ein wichtiger Schl\u00fcssel f\u00fcr gleichwertige Lebensverh\u00e4ltnisse im ganzen Freistaat \u2013 dieses Ziel hat in Bayern Verfassungsrang. Wir brauchen eine zukunftsfeste Internetanbindung aller bayerischen Haushalte.\u201c, sagte Finanzminister Albert F\u00fcracker anl\u00e4sslich der Unterzeichnung. Gleichzeitig k\u00fcndigte er an, dass mit dem unterzeichneten LOI auch moderne Verlegeverfahren (<a href=\"https:\/\/www.glasfaser-internet.info\/technik\/trenching.html\" data-internallinksmanager029f6b8e52c=\"48\" title=\"Trenching\">Trenching<\/a>) eingesetzt werden sollen. Auch um Kosten zu sparen.<\/p>\n<h3>L\u00e4ndlichen Raum zukunftssicher machen<\/h3>\n<p>\u201cWir freuen uns darauf, in den n\u00e4chsten vier Jahren entscheidend zum fl\u00e4chendeckenden <a href=\"https:\/\/www.glasfaser-internet.info\/ausbau\/glasfaser-ausbau.html\" data-internallinksmanager029f6b8e52c=\"1\" title=\"alles zum aktuellen Stand des FTTH-Ausbaus\">Glasfaserausbau<\/a> in Bayern beizutragen und seine l\u00e4ndlichen und suburbanen Regionen zukunftssicher zu machen&#8220;, erg\u00e4nzt Deutsche Glasfaser CEO Dirks.<\/p>\n<p>&nbsp;<\/p>\n<p>Mit der neuen Vereinbarung unterstreicht der Freistaat Bayern die Notwendigkeit von effizienter Zusammenarbeit von Privatwirtschaft und staatlichen Stellen beim Ausbau der digitalen Infrastruktur. F\u00fcr das Unternehmen ist die Zusammenarbeit mit einem Bundesland nichts Neues. \u00c4hnliche Vereinbarungen gibt es bereits mit dem Saarland, Sachsen-Anhalt und Hessen. Deutsche Glasfaser hat das Ziel, die Anzahl an <a href=\"https:\/\/www.glasfaser-internet.info\/ratgeber\/glasfaser-anschluss.html\" data-internallinksmanager029f6b8e52c=\"2\" title=\"alles \u00fcber Glasfaser-Anschl\u00fcsse erfahren\">Glasfaseranschl\u00fcssen<\/a> in den kommenden Jahren auf 6 Millionen auszubauen. Bis Ende 2025 sollen es alleine 4 Millionen sein. Hierf\u00fcr investiert das Unternehmen insgesamt etwa 7 Milliarden Euro.<\/p>\n<h3>Hilfreiches zum Beitrag:<\/h3>\n<p>\u00bb <a href=\"https:\/\/www.glasfaser-internet.info\/verfuegbarkeit\/glasfaser-verfuegbarkeit-testen.html\">Glasfaser Karte<\/a><\/p>\n<div class=\"quellenews\">\nQuelle: Deutsche Glasfaser\n<\/div>\n<div style='text-align:center' class='yasr-auto-insert-visitor'><\/div>","protected":false},"excerpt":{"rendered":"<p>Deutsche Glasfaser hat heute bekanntgegeben, dass man bis Ende 2025 etwa 550.000 Haushalte in Bayern mit Glasfaser versorgen will. Der Ausbau wird vorrangig eigenwirtschaftlich erfolgen, aber von der Regierung des Freistaats unterst\u00fctzt.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","iawp_total_views":8,"footnotes":"","jetpack_post_was_ever_published":false,"_wp_rev_ctl_limit":""},"categories":[19,359],"tags":[105,68,9],"class_list":["post-3379","post","type-post","status-publish","format-standard","hentry","category-ausbau","category-dt-glasfaser","tag-bayern","tag-deutsche-glasfaser","tag-glasfaserausbau"],"views":720,"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":0,"sum_votes":0},"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/posts\/3379","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/comments?post=3379"}],"version-history":[{"count":2,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/posts\/3379\/revisions"}],"predecessor-version":[{"id":7752,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/posts\/3379\/revisions\/7752"}],"wp:attachment":[{"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/media?parent=3379"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/categories?post=3379"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/tags?post=3379"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}