{"id":2922,"date":"2021-06-04T11:49:52","date_gmt":"2021-06-04T11:49:52","guid":{"rendered":"https:\/\/www.glasfaser-internet.info\/fiber-news\/?p=2922"},"modified":"2021-06-04T11:49:52","modified_gmt":"2021-06-04T11:49:52","slug":"glasfaseranschluesse-fuer-300-000-haushalte-in-sachsen-anhalt","status":"publish","type":"post","link":"https:\/\/www.glasfaser-internet.info\/fiber-news\/glasfaseranschluesse-fuer-300-000-haushalte-in-sachsen-anhalt","title":{"rendered":"Glasfaseranschl\u00fcsse f\u00fcr 300.000 Haushalte in Sachsen-Anhalt"},"content":{"rendered":"<p>Die <a href=\"https:\/\/www.glasfaser-internet.info\/anbieter\/deutsche-glasfaser.html\" data-internallinksmanager029f6b8e52c=\"18\" title=\"FTTH-Tarife der Deutschen Glasfaser zeigen\">Deutsche Glasfaser<\/a> hat heute bekanntgegeben, dass das Unternehmen bis 2025 300.000 Haushalte in Sachsen-Anhalt mit <a href=\"https:\/\/www.glasfaser-internet.info\/ratgeber\/glasfaser-anschluss.html\" data-internallinksmanager029f6b8e52c=\"2\" title=\"alles \u00fcber Glasfaser-Anschl\u00fcsse erfahren\">Glasfaseranschl\u00fcssen<\/a> versorgen will. Eine entsprechende Absichtserkl\u00e4rung haben das Unternehmen und das Wirtschaftsministerium unterzeichnet.<!--more--><\/p>\n<h3>Absichtserkl\u00e4rung unterzeichnet<\/h3>\n<p>Die Deutsche Glasfaser wird bis 2025 300.000 neue Glasfaseranschl\u00fcsse in Sachsen-Anhalt bauen. Sachsen-Anhalts Wirtschaftsminister Prof. Dr. Armin Willingmann und der CEO der Deutsche Glasfaser Holding GmbH, Thorsten Dirks, haben am heutigen Freitag einen entsprechenden \u201eLetter of Intent\u201c unterzeichnet. \u201eNach dem im Februar abgeschlossenen Glasfaserpakt mit 23 Partnern gehen wir mit der heutigen Absichtserkl\u00e4rung einen weiteren gro\u00dfen Schritt in Richtung Gigabitgesellschaft und fl\u00e4chendeckenden <a href=\"https:\/\/www.glasfaser-internet.info\/ausbau\/glasfaser-ausbau.html\">Glasfaserausbau<\/a>\u201c, betonte Willingmann. \u201eWir setzen unsere Gigabitstrategie konsequent um. Erfreulich ist die klare Fokussierung der Deutschen Glasfaser auf eigenwirtschaftlichen Ausbau, ebenso aber auch die Bereitschaft, sich am gef\u00f6rderten Breitbandausbau zu beteiligen.\u201c<\/p>\n<p>&nbsp;<\/p>\n<p>CEO Thorsten Dirks erkl\u00e4rte: \u201eDeutsche Glasfaser ist der f\u00fchrende Glasfaserversorger f\u00fcr den l\u00e4ndlichen Raum in Deutschland. Dabei setzen wir insbesondere auf eine enge Zusammenarbeit mit allen Beteiligten \u2013 von der Landespolitik \u00fcber die Kommunen bis zu den B\u00fcrgerinnen und B\u00fcrgern. Wir freuen uns im Schulterschluss mit dem Land Sachsen-Anhalt nun den fl\u00e4chendeckenden <a href=\"https:\/\/www.glasfaser-internet.info\/ausbau\/glasfaser-ausbau.html\" data-internallinksmanager029f6b8e52c=\"1\" title=\"alles zum aktuellen Stand des FTTH-Ausbaus\">Glasfaserausbau<\/a> landesweit, schnell und unb\u00fcrokratisch voranzutreiben. So schaffen wir ein digitales B\u00fcrgernetz und leisten gemeinsam einen Beitrag f\u00fcr den Wohlstand in den Regionen.\u201c<\/p>\n<h3>300.000 neue Glasfaseranschl\u00fcsse in Sachsen-Anhalt<\/h3>\n<p>Die Absichtserkl\u00e4rung h\u00e4lt klare Absprachen \u00fcber den Glasfaserausbau fest. Derzeit baut die Deutsche Glasfaser bereits f\u00fcr die ersten 22.000 Haushalte Glasfaseranschl\u00fcsse aus. Zudem bereitet sie die <a href=\"https:\/\/www.glasfaser-internet.info\/faq\/ftth-vs-glasfaser.html\" data-internallinksmanager029f6b8e52c=\"8\" title=\"Was ist FTTH?\">FTTH<\/a>-Anbindung (\u201e<a href=\"https:\/\/www.glasfaser-internet.info\/faq\/ftth-vs-glasfaser.html\">Fiber To The Home<\/a>\u201c \u2013 Glasfaser bis ins Haus) f\u00fcr weitere 140.000 Haushalte vor. Die Ausbaugeschwindigkeit soll in den kommenden Jahren noch weiter gesteigert werden, damit bis Ende 2025 300.000 Haushalte mit Glasfaser versorgt sind.<\/p>\n<p>&nbsp;<\/p>\n<p>Auch dank dieser Aktivit\u00e4ten, hat sich der Breitbandausbau in Sachsen-Anhalt in den vergangenen Jahren stark beschleunigt. Laut aktuellem Breitbandatlas des Bundesministeriums f\u00fcr Verkehr und digitale Infrastruktur verf\u00fcgten Ende 2020 gut 87 Prozent aller Haushalte in dem Bundesland \u00fcber Internetanschl\u00fcsse mit mindestens 50 Megabit pro Sekunde Downloadrate. Damit weist Sachsen-Anhalt die h\u00f6chste Zuwachsrate aller ostdeutschen Fl\u00e4chenl\u00e4nder auf. Die Quote an Gigabitanschl\u00fcssen lag Ende vergangenen Jahres bei 19,1 Prozent.<\/p>\n<div class=\"quellenews\">\nQuelle: Deutsche Glasfaser\n<\/div>\n<div style='text-align:center' class='yasr-auto-insert-visitor'><\/div>","protected":false},"excerpt":{"rendered":"<p>Die Deutsche Glasfaser hat heute bekanntgegeben, dass das Unternehmen bis 2025 300.000 Haushalte in Sachsen-Anhalt mit Glasfaseranschl\u00fcssen versorgen will. Eine entsprechende Absichtserkl\u00e4rung haben das Unternehmen und das Wirtschaftsministerium unterzeichnet.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","iawp_total_views":5,"footnotes":"","jetpack_post_was_ever_published":false,"_wp_rev_ctl_limit":""},"categories":[1,19,359,27],"tags":[174,68,501],"class_list":["post-2922","post","type-post","status-publish","format-standard","hentry","category-allgemein","category-ausbau","category-dt-glasfaser","category-ftth-provider","tag-ausbau","tag-deutsche-glasfaser","tag-sachsen-anhalt"],"views":869,"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":0,"sum_votes":0},"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/posts\/2922","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/comments?post=2922"}],"version-history":[{"count":0,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/posts\/2922\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/media?parent=2922"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/categories?post=2922"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/tags?post=2922"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}