{"id":2883,"date":"2021-05-21T13:17:35","date_gmt":"2021-05-21T13:17:35","guid":{"rendered":"https:\/\/www.glasfaser-internet.info\/fiber-news\/?p=2883"},"modified":"2022-02-17T10:24:59","modified_gmt":"2022-02-17T10:24:59","slug":"telekom-118-000-haushalte-haben-schnelleres-internet-bekommen","status":"publish","type":"post","link":"https:\/\/www.glasfaser-internet.info\/fiber-news\/telekom-118-000-haushalte-haben-schnelleres-internet-bekommen","title":{"rendered":"Telekom: 118.000 Haushalte haben schnelleres Internet bekommen"},"content":{"rendered":"<p>Die Telekom baut ihr Breitbandnetz stetig weiter aus. Im April wurden 118.000 Haushalte mit einer h\u00f6heren Internet-Geschwindigkeit versorgt, die nun bei der Telekom gebucht werden k\u00f6nnen.<!--more--><\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-content\/uploads\/2021\/03\/glasfaser-inside.jpg\" alt=\"Glasfaser-Ausbau\" \/><\/p>\n<h3>690.000 Haushalte seit Jahresbeginn<\/h3>\n<p>Die Telekom hat heute bekanntgegeben, dass vom Breitbandausbau im zur\u00fcckliegenden April 2021 \u00fcber 100.000 Haushalte profitieren. F\u00fcr rund 118.000 Haushalte wurde die Internet-Geschwindigkeit durch den Ausbau erh\u00f6ht. Die betroffenen Haushalte k\u00f6nnen nun einen schnelleren Tarif bei der Telekom buchen, wenn sie von den neuen M\u00f6glichkeiten profitieren m\u00f6chten. Seit Jahresbeginn haben fast 700.000 Haushalte von den Ausbauma\u00dfnahmen der Telekom profitiert.<\/p>\n<p>&nbsp;<\/p>\n<p>Insgesamt erm\u00f6glicht die <a href=\"https:\/\/www.glasfaser-internet.info\/anbieter\/telekom-ftth.html\" data-internallinksmanager029f6b8e52c=\"14\" title=\"Glasfaser-Tarife der Telekom zeigen\">Deutsche Telekom<\/a> mit ihrem gut ausgebauten Netz nun 34,1 Millionen Haushalten einen <a href=\"https:\/\/www.glasfaser-internet.info\/alternativen\/vdsl.html\" data-internallinksmanager029f6b8e52c=\"11\" title=\"alles \u00fcber VDSL-Anschl\u00fcsse erfahren\">VDSL<\/a>-Tarif mit bis zu 100 Megabit pro Sekunde (Mbit\/s) oder mehr, der beim Konzern gebucht werden kann. F\u00fcr 25,8 Millionen Haushalte ist ein Tarif mit bis zu 250 MBit\/s oder mehr m\u00f6glich. Einen reinen <a href=\"https:\/\/www.glasfaser-internet.info\/ratgeber\/glasfaser-anschluss.html\" data-internallinksmanager029f6b8e52c=\"2\" title=\"alles \u00fcber Glasfaser-Anschl\u00fcsse erfahren\">Glasfaseranschluss<\/a> haben mittlerweile 2,3 Millionen Haushalte. Hier ist die Anzahl im vergangenen Monat um 45.000 angestiegen. Per Glasfaser sind Geschwindigkeiten bis zu einem <a href=\"https:\/\/www.glasfaser-internet.info\/tarife\/glasfaser1000.html\" data-internallinksmanager029f6b8e52c=\"54\" title=\"Anbieter und Kosten f\u00fcr 1000 MBit\/s\">Gigabit<\/a> pro Sekunde m\u00f6glich. Mehr zu den Preisen hier in der <a href=\"https:\/\/www.glasfaser-internet.info\/anbieter\/telekom-ftth.html\">Telekom-Tarif\u00fcbersicht Glasfaser<\/a>.<\/p>\n<h3>Telekom bleibt Marktf\u00fchrer<\/h3>\n<p>Die Telekom ist mit ihrem umfangreichen und gut ausgebauten Netz der gr\u00f6\u00dfte Anbieter in Deutschland, wenn es um die schnelle Internetversorgung von Haushalten geht. \u201eDie Zahlen belegen, dass wir der Breitband-Motor in Deutschland sind \u2013 f\u00fcr Festnetz und Mobilfunk\u201c, sagt Walter Goldenits, Gesch\u00e4ftsf\u00fchrer Technologie der Telekom Deutschland. \u201eWir bieten schnelles Internet f\u00fcr Millionen und nicht Topspeed f\u00fcr ganz wenige. Und wir machen das in bester Netzqualit\u00e4t.\u201c<\/p>\n<p>&nbsp;<\/p>\n<p>Dass die Telekom nicht nur Masse macht, sondern auch auf die Qualit\u00e4t der eigenen Leistung achtet, belegt zuletzt die Fachzeitschrift \u201eChip\u201c. Sie hat im April die Festnetzanbieter in Deutschland miteinander verglichen. Das Ergebnis ist, dass das Netz der Telekom mit der Gesamtnote von 1,5 im nationalen Vergleich auf dem ersten Platz steht. Kein anderer Anbieter konnte in der Kategorie die Note \u201esehr gut\u201c erzielen.<\/p>\n<div class=\"quellenews\">\nQuelle: Deutsche Telekom\n<\/div>\n<div style='text-align:center' class='yasr-auto-insert-visitor'><\/div>","protected":false},"excerpt":{"rendered":"<p>Die Telekom baut ihr Breitbandnetz stetig weiter aus. Im April wurden 118.000 Haushalte mit einer h\u00f6heren Internet-Geschwindigkeit versorgt, die nun bei der Telekom gebucht werden k\u00f6nnen.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","iawp_total_views":12,"footnotes":"","jetpack_post_was_ever_published":false,"_wp_rev_ctl_limit":""},"categories":[19],"tags":[495,174,119],"class_list":["post-2883","post","type-post","status-publish","format-standard","hentry","category-ausbau","tag-april-2021","tag-ausbau","tag-deutsche-telekom"],"views":944,"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":0,"sum_votes":0},"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/posts\/2883","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/comments?post=2883"}],"version-history":[{"count":0,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/posts\/2883\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/media?parent=2883"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/categories?post=2883"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/tags?post=2883"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}