{"id":230,"date":"2012-07-14T13:25:09","date_gmt":"2012-07-14T13:25:09","guid":{"rendered":"http:\/\/www.glasfaser-internet.info\/fiber-news\/?p=230"},"modified":"2012-07-16T13:28:56","modified_gmt":"2012-07-16T13:28:56","slug":"grunes-licht-fur-kooperationsmodell-der-telekom","status":"publish","type":"post","link":"https:\/\/www.glasfaser-internet.info\/fiber-news\/grunes-licht-fur-kooperationsmodell-der-telekom","title":{"rendered":"Gr\u00fcnes Licht f\u00fcr Kooperationsmodell der Telekom"},"content":{"rendered":"<p>Anfang des Jahres hatte die Bundesnetzagentur eine geplante Kooperation zwischen der Deutschen Telekom und <a href=\"https:\/\/www.glasfaser-internet.info\/anbieter\/netcologne.html\" data-internallinksmanager029f6b8e52c=\"17\" title=\"Netcologne Glasfaser-Tarife zeigen\">NetCologne<\/a> zum <a href=\"https:\/\/www.glasfaser-internet.info\/ausbau\/glasfaser-ausbau.html\" data-internallinksmanager029f6b8e52c=\"1\" title=\"alles zum aktuellen Stand des FTTH-Ausbaus\">Glasfaserausbau<\/a> untersagt. Nun genehmigte die Bundesnetzagentur ein von der Telekom \u00fcberarbeitetes Modell f\u00fcr die Kooperation mit anderen Telekommunikationsanbietern. Dem Breitbandausbau in Deutschland wird dies einen gro\u00dfen Schub geben. <!--more--><\/p>\n<h3>Korrekturen stellen Beh\u00f6rde zufrieden<\/h3>\n<p>Mit einem \u00fcberarbeiteten Kooperationsmodell, konnte die Telekom die Bedenken der Bundesnetzagentur zum ersten Entwurf des Kontingentmodells nun aus der Welt r\u00e4umen. Durch das Einbringen eines Sonderk\u00fcndigungsrechts in den Kooperationsvertr\u00e4gen und einer Verkleinerung der Mindestkontingentgr\u00f6\u00dfe, beseitigte die Telekom die wesentlichen Kritikpunkte der Bundesnetzagentur. &#8222;Dass wir diese H\u00fcrde genommen haben, bringt den Breitbandausbau entscheidend voran\u201c, sagte Niek Jan van Damme, Vorstand der Deutschen Telekom. \u201eNur durch Kooperationen kann der Netzausbau der n\u00e4chsten Generation gelingen. Die Branche muss sich Kosten und Risiken teilen k\u00f6nnen, wenn sie Milliarden investieren soll&#8220;, unterstrich van Damme die Bedeutung der Entscheidung.<\/p>\n<h3>Erster Versuch war gescheitert<\/h3>\n<p>Breitbandanschl\u00fcsse gro\u00dffl\u00e4chig anzubieten kostet Telekommunikationsunternehmen Unmengen an Geld \u2013 deswegen sind sie f\u00fcr den Ausbau ihres Glasfasernetzes auf Kooperationen angewiesen. Im Januar hatte die Telekom angek\u00fcndigt, direkt mit dem K\u00f6lner Kommunikationsunternehmen NetCologne zu kooperieren. Die Bundesnetzagentur untersagte die Zusammenarbeit nach dem sogenannten Kontingentmodell aber, bei dem die Telekom eine bestimmte Anzahl an <a href=\"https:\/\/www.glasfaser-internet.info\/ratgeber\/glasfaser-anschluss.html\" data-internallinksmanager029f6b8e52c=\"2\" title=\"alles \u00fcber Glasfaser-Anschl\u00fcsse erfahren\">Glasfaseranschl\u00fcssen<\/a> vom K\u00f6lner Anbieter gebucht h\u00e4tte, und dieser im Gegenzug <a href=\"https:\/\/www.glasfaser-internet.info\/alternativen\/vdsl.html\" data-internallinksmanager029f6b8e52c=\"11\" title=\"alles \u00fcber VDSL-Anschl\u00fcsse erfahren\">VDSL<\/a>-Anschl\u00fcsse von der Telekom gemietet h\u00e4tte. Darauf hatte sich das Unternehmen intensiv mit den Kritikpunkten der Beh\u00f6rde auseinandergesetzt, um nicht auf die so wichtigen Kooperationen verzichten zu m\u00fcssen.<\/p>\n<h3>Kooperationen sind notwendig<\/h3>\n<p>Die Telekom m\u00f6chte nach eigenen Aussagen ihre Kooperationen weiter ausbauen. Diesbez\u00fcglich sollen wohl auch schon weitere Unternehmen ihr Interesse an einer Zusammenarbeit f\u00fcr den Glasfaserausbau angek\u00fcndigt haben. Seit Anfang des Jahres 2012 setzt die Telekom verst\u00e4rkt auf Kooperationen beim kostenintensiven <a href=\"https:\/\/www.glasfaser-internet.info\/ausbau\/glasfaser-ausbau.html\">Glasfaserausbau<\/a>\u2013 neben der (wegen der Bundesnetzagentur aufgeschobenen) Kooperationen mit anderen Telekommunikationsanbietern, wie NetCologne, kam es so auch verst\u00e4rkt zu Zusammenarbeiten mit lokalen Energieversorgern. Insgesamt will die Telekom in 2012 in acht weiteren St\u00e4dten Glasfaser bis in die Wohnung der Kunden anbieten. Nachdem das Kontingentmodell nun von der Bundesnetzagentur genehmigt wurde, k\u00f6nnte dem z\u00fcgigen Ausbau nur noch die EU-Kommission einen Strich durch die Rechnung machen. Das gilt aber als eher unwahrscheinlich. <\/p>\n<h3>Hilfreiches zum Artikel:<\/h3>\n<p>\u00bb <a href=\"https:\/\/www.glasfaser-internet.info\/anbieter\/telekom-ftth.html\">FTTH von der Telekom<\/a><br \/>\n\u00bb <a href=\"https:\/\/www.glasfaser-internet.info\/verfuegbarkeit\/glasfaser-verfuegbarkeit-testen.html\">Karte zur Glasfaser Verf\u00fcgbarkeit <\/a><\/p>\n<div class=\"quellenews\">\nQuelle: <a href=\"https:\/\/www.glasfaser-internet.info\/anbieter\/telekom-ftth.html\" data-internallinksmanager029f6b8e52c=\"14\" title=\"Glasfaser-Tarife der Telekom zeigen\">Deutsche Telekom<\/a>\n<\/div>\n<div style='text-align:center' class='yasr-auto-insert-visitor'><\/div>","protected":false},"excerpt":{"rendered":"<p>Anfang des Jahres hatte die Bundesnetzagentur eine geplante Kooperation zwischen der Deutschen Telekom und NetCologne zum Glasfaserausbau untersagt. Nun genehmigte die Bundesnetzagentur ein von der Telekom \u00fcberarbeitetes Modell f\u00fcr die Kooperation mit anderen Telekommunikationsanbietern. Dem Breitbandausbau in Deutschland wird dies einen gro\u00dfen Schub geben.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","iawp_total_views":4,"footnotes":"","jetpack_post_was_ever_published":false,"_wp_rev_ctl_limit":""},"categories":[19,28],"tags":[174,50,3,18,49,6],"class_list":["post-230","post","type-post","status-publish","format-standard","hentry","category-ausbau","category-telekom-ftth-provider","tag-ausbau","tag-bundesnetzagentur","tag-glasfaser","tag-kooperation","tag-netcologne-2","tag-telekom"],"views":4404,"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":1,"sum_votes":5},"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/posts\/230","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/comments?post=230"}],"version-history":[{"count":0,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/posts\/230\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/media?parent=230"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/categories?post=230"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/tags?post=230"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}