{"id":1479,"date":"2018-03-28T17:14:20","date_gmt":"2018-03-28T17:14:20","guid":{"rendered":"http:\/\/www.glasfaser-internet.info\/fiber-news\/?p=1479"},"modified":"2018-03-29T07:42:48","modified_gmt":"2018-03-29T07:42:48","slug":"im-landkreis-bautzen-wird-gigabit-glasfaser-der-telekom-ausgebaut","status":"publish","type":"post","link":"https:\/\/www.glasfaser-internet.info\/fiber-news\/im-landkreis-bautzen-wird-gigabit-glasfaser-der-telekom-ausgebaut","title":{"rendered":"Im Landkreis Bautzen wird Gigabit-Glasfaser der Telekom ausgebaut"},"content":{"rendered":"<p>Kaum eine Woche vergeht momentan ohne eine neue Ausbau-Meldung der Telekom &#8211; diesmal ist wieder das Glasfaser an der Reihe. Der Bonner Konzern lie\u00df verlautbaren, dass in Zukunft im Landkreis Bautzen <a href=\"https:\/\/www.glasfaser-internet.info\/tarife\/glasfaser1000.html\" data-internallinksmanager029f6b8e52c=\"54\" title=\"Anbieter und Kosten f\u00fcr 1000 MBit\/s\">1 Gbit\/s<\/a> via <a href=\"https:\/\/www.glasfaser-internet.info\/faq\/ftth-vs-glasfaser.html\" data-internallinksmanager029f6b8e52c=\"8\" title=\"Was ist FTTH?\">FTTH<\/a> f\u00fcr rund 56.000 Haushalte und Unternehmen zur Verf\u00fcgung stehen. Die Arbeiten sollen noch im ersten Halbjahr 2018 beginnen und Ende 2020 abgeschlossen sein.<!--more--><\/p>\n<h3>Turbo-Internet f\u00fcr eine Drittel Million Bundesb\u00fcrger<\/h3>\n<p>Der im Bundesland Sachsen befindliche Landkreis Bautzen weist eine Bev\u00f6lkerungsdichte von \u00fcber 305.000 Einwohner auf. Das Gebiet erstreckt sich \u00fcber eine Fl\u00e4che von knapp 2.400 km\u00b2. Das von der <a href=\"https:\/\/www.glasfaser-internet.info\/anbieter\/telekom-ftth.html\">Telekom<\/a> j\u00fcngst angek\u00fcndigte Ausbauprojekt ist also \u00fcberaus ambitioniert und soll bei 56.000 Haushalten und Unternehmen in 57 Kommunen den Daten-Turbo z\u00fcnden. Bis zu 1 Gbit\/s im Download und maximal <a href=\"https:\/\/www.glasfaser-internet.info\/tarife\/glasfaser500-600.html\" data-internallinksmanager029f6b8e52c=\"52\" title=\"alle Anbieter und Preise f\u00fcr Glasfaser mit 500-600 MBit\">500 Mbit\/s<\/a> im <a href=\"https:\/\/www.glasfaser-internet.info\/speed\/glasfaser-upload.html\" data-internallinksmanager029f6b8e52c=\"9\" title=\"mehr zum Thema Upload bei Glasfaser-Tarifen erfahren\">Upload<\/a> soll es geben. Die Wohnungen und H\u00e4user werden via <a href=\"https:\/\/www.glasfaser-internet.info\/faq\/ftth-vs-glasfaser.html\">FTTH<\/a> (Fibre to the Home) direkt an das Glasfasernetz angeschlossen. Es ist geplant, 4.000 Kilometer an Glasfaserkabel zu verlegen, dabei finden Tiefbauarbeiten mit 1.500 Kilometer statt. Diese Bauweise hat den Vorteil, dass sie kosteneffizient ist und schnell umgesetzt werden kann. Das schont den Geldbeutel des Netzbetreibers und die Nerven der Anwohner. In den kommenden Wochen und Monaten wird die Telekom Immobilieneigent\u00fcmer schriftlich benachrichtigen, um die Einwilligungen f\u00fcr die Umbauarbeiten an und in den H\u00e4usern des Gebiets einzuholen.<\/p>\n<h3>Stimmen zum Glasfaserausbau in Bautzen<\/h3>\n<p>Michael Harig, Landrat des Landkreises und Dr. Vesta von Bossel, Vorstandsbeauftragte der Telekom-Abteilung Breitbandausbau, meldeten sich bereits zu Wort. Der Landreis zeigt sich begeistert von der Gigabit-Zukunft seiner Region: \u201eIch freue mich, dass unser gr\u00f6\u00dftes Infrastrukturprojekt nun in die Umsetzung gehen kann. Die landkreisweite Versorgung mit schnellem Internet wirkt sich positiv auf den Wert der Grundst\u00fccke aus und erh\u00f6ht die Attraktivit\u00e4t des l\u00e4ndlichen Raumes f\u00fcr die Menschen und auch f\u00fcr die Wirtschaft&#8220;. Die Telekom-Mitarbeiterin ist erfreut \u00fcber das Vertrauen von Bautzen und beschreibt sich selbst als &#8222;die Glasfaser Company&#8220;. Von der Expertise des Netzbetreibers w\u00fcrden der Landkreis und die Kunden profitieren.<\/p>\n<div style='text-align:center' class='yasr-auto-insert-visitor'><\/div>","protected":false},"excerpt":{"rendered":"<p>Kaum eine Woche vergeht momentan ohne eine neue Ausbau-Meldung der Telekom &#8211; diesmal ist wieder das Glasfaser an der Reihe. Der Bonner Konzern lie\u00df verlautbaren, dass in Zukunft im Landkreis Bautzen 1 Gbit\/s via FTTH f\u00fcr rund 56.000 Haushalte und Unternehmen zur Verf\u00fcgung stehen. Die Arbeiten sollen noch im ersten Halbjahr 2018 beginnen und Ende [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","iawp_total_views":2,"footnotes":"","jetpack_post_was_ever_published":false,"_wp_rev_ctl_limit":""},"categories":[19,28,27],"tags":[174,287,4,3,259,6],"class_list":["post-1479","post","type-post","status-publish","format-standard","hentry","category-ausbau","category-telekom-ftth-provider","category-ftth-provider","tag-ausbau","tag-bautzen","tag-ftth","tag-glasfaser","tag-sachsen","tag-telekom"],"views":2473,"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":5,"sum_votes":11},"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/posts\/1479","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/comments?post=1479"}],"version-history":[{"count":0,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/posts\/1479\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/media?parent=1479"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/categories?post=1479"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.glasfaser-internet.info\/fiber-news\/wp-json\/wp\/v2\/tags?post=1479"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}